{"id":31965,"date":"2018-07-25T13:37:28","date_gmt":"2018-07-25T11:37:28","guid":{"rendered":"https:\/\/pelletterieded.lisa.simonechinaglia.net\/negozio\/shopping-donna-26\/"},"modified":"2025-11-24T09:47:56","modified_gmt":"2025-11-24T08:47:56","slug":"cartella-messenger","status":"publish","type":"product","link":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/business\/cartella-messenger\/","title":{"rendered":"Cartella Messenger"},"content":{"rendered":"<p>Realizzata completamente in Italia da abili pellettieri mediante l\u2019utilizzo di un pellame bovino conciato con tannini vegetali e successivamente tamponato a mano.<\/p>\n<p>La caratteristica di questo pellame naturale offre una piacevolezza al tatto e uno stile inconfondibile della pelletteria italiana.<\/p>\n<p>La vendita dell\u2019oggetto viene gestita direttamente dall\u2019azienda che lo produce<\/p>\n<p><strong>ESTERNI:<\/strong><\/p>\n<p>\u2013 pelle pieno fiore conciata la vegetale e tamponata a mano<\/p>\n<p>\u2013 costruzione semi morbida<\/p>\n<p>\u2013 chiusura con tuc (chiave in dotazione)<\/p>\n<p>\u2013 manico in pelle<\/p>\n<p>\u2013 due tasche frontali<\/p>\n<p>\u2013 tasca frontale con chiusura a zip<\/p>\n<p>\u2013 tasca posteriore con chiusura a zip<\/p>\n<p>\u2013 tracolla in pelle regolabile e rimovibile<\/p>\n<p>\u2013 accessori in metallo<\/p>\n<p><strong>INTERNI:<\/strong><\/p>\n<p>\u2013 rivestimento interno in tessuto<\/p>\n<p>\u2013 due scomparti<\/p>\n<p>\u2013 tasca con chiusura a zip e bavero in pelle<\/p>\n<p>\u2013 tasca porta pc<\/p>\n<p>\u2013 due tasche adiacenti porta oggetti<\/p>\n<p>\u2013 tasca porta carte e penne in pelle<\/p>\n<p>\u2013 accessori in metallo<\/p>\n<p><strong>ACCESSORI:<\/strong><\/p>\n<p>\u2013 accessori in ottone spazzolato (sulle varianti colore marroni)<\/p>\n<p>\u2013 accessori palladio (sulle varianti colore rosso e nero)<\/p>\n<p><strong>DIMENSIONI:<\/strong><\/p>\n<p>Larghezza: 42cm | Altezza: 28cm | Profondit\u00e0: 12cm | Peso 1,6 Kg<\/p>\n<p><strong>CUSTODIA PROTETTIVA<\/strong>: sacchetto anti polvere incluso.<\/p>\n<p><strong>GARANZIA<\/strong>: 24 mesi.<\/p>\n<p><strong>CODICE INTERNO<\/strong>: 0706.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cartella Messenger <\/strong>100% Made in Italy realizzata\u00a0<strong>in\u00a0vero cuoio\u00a0<\/strong>Toscano con tracolla in pelle rimovibile e regolabile.<br \/>\nAmpia, comoda e <strong>e dagli spazi ben strutturati<\/strong>, quasta cartella da lavoro semi morbida\u00a0 dona un look giovaniele e professionale.<br \/>\nIdeale per liberi professionisti.<\/p>\n<p><strong>Larghezza:<\/strong> 42cm | <strong>Altezza:<\/strong> 28cm | <strong>Profondit\u00e0:<\/strong> 12cm | <strong>Peso<\/strong> 1,6 Kg<\/p>\n","protected":false},"featured_media":124403,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1354,327,366,342],"product_tag":[1353],"class_list":{"0":"post-31965","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-black-friday","7":"product_cat-business","8":"product_cat-cartelle","9":"product_cat-porta-pc","10":"product_tag-bf","12":"first","13":"instock","14":"shipping-taxable","15":"purchasable","16":"product-type-variable","17":"has-default-attributes","18":"wvs-archive-product-wrapper"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cartella Messenger - Pelletterie D&amp;D<\/title>\n<meta name=\"description\" content=\"Cartella Messenger 100% Made in Italy realizzata\u00a0in\u00a0vero cuoio\u00a0Toscano con tracolla in pelle rimovibile e regolabile.Cartella Messenger 100% Made in Italy realizzata\u00a0in\u00a0vero cuoio\u00a0Toscano con tracolla in pelle rimovibile e regolabile.Ampia, comoda e pratica, dalle linee semi morbide quasta cartella da lavoro dona un look giovaniele e professionale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pelletterieded.com\/it\/shop\/uomo\/business\/cartella-messenger\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartella Messenger - Pelletterie D&amp;D\" \/>\n<meta property=\"og:description\" content=\"Cartella Messenger 100% Made in Italy realizzata\u00a0in\u00a0vero cuoio\u00a0Toscano con tracolla in pelle rimovibile e regolabile.Cartella Messenger 100% Made in Italy realizzata\u00a0in\u00a0vero cuoio\u00a0Toscano con tracolla in pelle rimovibile e regolabile.Ampia, comoda e pratica, dalle linee semi morbide quasta cartella da lavoro dona un look giovaniele e professionale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pelletterieded.com\/it\/shop\/uomo\/business\/cartella-messenger\/\" \/>\n<meta property=\"og:site_name\" content=\"Pelletterie D&amp;D\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dedpelletterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-24T08:47:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0706-marrone-scaled-jpg.avif\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/business\\\/cartella-messenger\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/business\\\/cartella-messenger\\\/\",\"name\":\"Cartella Messenger - Pelletterie D&amp;D\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/business\\\/cartella-messenger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/business\\\/cartella-messenger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/0706-marrone-scaled-jpg.avif\",\"datePublished\":\"2018-07-25T11:37:28+00:00\",\"dateModified\":\"2025-11-24T08:47:56+00:00\",\"description\":\"Cartella Messenger 100% Made in Italy realizzata\u00a0in\u00a0vero cuoio\u00a0Toscano con tracolla in pelle rimovibile e regolabile.Cartella Messenger 100% Made in Italy realizzata\u00a0in\u00a0vero cuoio\u00a0Toscano con tracolla in pelle rimovibile e regolabile.Ampia, comoda e pratica, dalle linee semi morbide quasta cartella da lavoro dona un look giovaniele e professionale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/business\\\/cartella-messenger\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/business\\\/cartella-messenger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/business\\\/cartella-messenger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/0706-marrone-scaled-jpg.avif\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/0706-marrone-scaled-jpg.avif\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/business\\\/cartella-messenger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pelletterie D&amp;D\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"shop\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Uomo\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/uomo\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Business\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/uomo\\\/business\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Cartella Messenger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/\",\"name\":\"Pelletterie D&D\",\"description\":\"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#organization\",\"name\":\"Pelletterie D&D\",\"alternateName\":\"D&D Pelletterie\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"width\":185,\"height\":200,\"caption\":\"Pelletterie D&D\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dedpelletterie\",\"https:\\\/\\\/www.instagram.com\\\/pelletterieded\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cartella Messenger - Pelletterie D&amp;D","description":"Cartella Messenger 100% Made in Italy realizzata\u00a0in\u00a0vero cuoio\u00a0Toscano con tracolla in pelle rimovibile e regolabile.Cartella Messenger 100% Made in Italy realizzata\u00a0in\u00a0vero cuoio\u00a0Toscano con tracolla in pelle rimovibile e regolabile.Ampia, comoda e pratica, dalle linee semi morbide quasta cartella da lavoro dona un look giovaniele e professionale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/business\/cartella-messenger\/","og_locale":"it_IT","og_type":"article","og_title":"Cartella Messenger - Pelletterie D&amp;D","og_description":"Cartella Messenger 100% Made in Italy realizzata\u00a0in\u00a0vero cuoio\u00a0Toscano con tracolla in pelle rimovibile e regolabile.Cartella Messenger 100% Made in Italy realizzata\u00a0in\u00a0vero cuoio\u00a0Toscano con tracolla in pelle rimovibile e regolabile.Ampia, comoda e pratica, dalle linee semi morbide quasta cartella da lavoro dona un look giovaniele e professionale.","og_url":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/business\/cartella-messenger\/","og_site_name":"Pelletterie D&amp;D","article_publisher":"https:\/\/www.facebook.com\/dedpelletterie","article_modified_time":"2025-11-24T08:47:56+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0706-marrone-scaled-jpg.avif","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/business\/cartella-messenger\/","url":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/business\/cartella-messenger\/","name":"Cartella Messenger - Pelletterie D&amp;D","isPartOf":{"@id":"https:\/\/pelletterieded.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/business\/cartella-messenger\/#primaryimage"},"image":{"@id":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/business\/cartella-messenger\/#primaryimage"},"thumbnailUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0706-marrone-scaled-jpg.avif","datePublished":"2018-07-25T11:37:28+00:00","dateModified":"2025-11-24T08:47:56+00:00","description":"Cartella Messenger 100% Made in Italy realizzata\u00a0in\u00a0vero cuoio\u00a0Toscano con tracolla in pelle rimovibile e regolabile.Cartella Messenger 100% Made in Italy realizzata\u00a0in\u00a0vero cuoio\u00a0Toscano con tracolla in pelle rimovibile e regolabile.Ampia, comoda e pratica, dalle linee semi morbide quasta cartella da lavoro dona un look giovaniele e professionale.","breadcrumb":{"@id":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/business\/cartella-messenger\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pelletterieded.com\/it\/shop\/uomo\/business\/cartella-messenger\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/business\/cartella-messenger\/#primaryimage","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0706-marrone-scaled-jpg.avif","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0706-marrone-scaled-jpg.avif","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/business\/cartella-messenger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pelletterie D&amp;D","item":"https:\/\/pelletterieded.com\/it\/"},{"@type":"ListItem","position":2,"name":"shop","item":"https:\/\/pelletterieded.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Uomo","item":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/uomo\/"},{"@type":"ListItem","position":4,"name":"Business","item":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/uomo\/business\/"},{"@type":"ListItem","position":5,"name":"Cartella Messenger"}]},{"@type":"WebSite","@id":"https:\/\/pelletterieded.com\/it\/#website","url":"https:\/\/pelletterieded.com\/it\/","name":"Pelletterie D&D","description":"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.","publisher":{"@id":"https:\/\/pelletterieded.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pelletterieded.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/pelletterieded.com\/it\/#organization","name":"Pelletterie D&D","alternateName":"D&D Pelletterie","url":"https:\/\/pelletterieded.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/pelletterieded.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","width":185,"height":200,"caption":"Pelletterie D&D"},"image":{"@id":"https:\/\/pelletterieded.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dedpelletterie","https:\/\/www.instagram.com\/pelletterieded\/"]}]}},"_links":{"self":[{"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product\/31965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/comments?post=31965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/media\/124403"}],"wp:attachment":[{"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/media?parent=31965"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product_brand?post=31965"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product_cat?post=31965"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product_tag?post=31965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}