{"id":189983,"date":"2025-07-30T08:33:09","date_gmt":"2025-07-30T06:33:09","guid":{"rendered":"https:\/\/pelletterieded.com\/?post_type=product&#038;p=189983"},"modified":"2026-02-10T08:29:31","modified_gmt":"2026-02-10T07:29:31","slug":"beauty-case-vernazza-100-made-in-italy","status":"publish","type":"product","link":"https:\/\/pelletterieded.com\/it\/shop\/borse-da-viaggio\/accessori-da-viaggio\/beauty-case-vernazza-100-made-in-italy\/","title":{"rendered":"Beauty Case Vernazza \u2013 100% Made in Italy"},"content":{"rendered":"<p><strong>Realizzato artigianalmente in vero cuoio toscano, il beauty case Vernazza racchiude l\u2019essenza dell\u2019eccellenza italiana. I riflessi multicolore, ispirati al fascino romantico della costa, restano impressi per sempre nel cuoio.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h5><strong>DESCRIZIONE GENERALE<\/strong><\/h5>\n<ul>\n<li>Pelle pieno fiore conciata al vegetale e tamponata a mano<\/li>\n<li>Design multicolore con lavorazione artigianale di alta qualit\u00e0<\/li>\n<li>100% Made in Italy<\/li>\n<\/ul>\n<h5><strong>ESTERNI<\/strong><\/h5>\n<ul>\n<li>Struttura semi-morbida<\/li>\n<li>Chiusura principale con zip<\/li>\n<li>Manico laterale in pelle<\/li>\n<li>Tasca frontale con chiusura a zip<\/li>\n<\/ul>\n<h5><strong>INTERNI<\/strong><\/h5>\n<ul>\n<li>Rivestimento interno in tessuto<\/li>\n<li>Due tasche adiacenti multiuso<\/li>\n<\/ul>\n<h5><strong>ACCESSORI<\/strong><\/h5>\n<ul>\n<li>Accessori in metallo di alta qualit\u00e0<\/li>\n<\/ul>\n<h5><strong>DIMENSIONI<\/strong><\/h5>\n<ul>\n<li><strong>Larghezza:<\/strong> 24 cm<\/li>\n<li><strong>Altezza:<\/strong> 14 cm<\/li>\n<li><strong>Profondit\u00e0:<\/strong> 14 cm<\/li>\n<li><strong>Peso:<\/strong> 0,4 kg<\/li>\n<\/ul>\n<h5><strong>CUSTODIA PROTETTIVA<\/strong><\/h5>\n<ul>\n<li>Sacchetto anti polvere non incluso<\/li>\n<\/ul>\n<h5><strong>GARANZIA<\/strong><\/h5>\n<h5><span style=\"color: #555555;\">24 mesi.<\/span><\/h5>\n<p>&nbsp;<\/p>\n<h5><strong>CODICE INTERNO<\/strong><\/h5>\n<ul>\n<li>art.0929<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Realizzato artigianalmente in vero cuoio toscano, il beauty case Vernazza racchiude l\u2019essenza dell\u2019eccellenza italiana. I riflessi multicolore, ispirati al fascino della costa, restano impressi per sempre nel cuoio. Ideale per tenere in ordine i tuoi oggetti personali con stile, anche in viaggio.<\/p>\n<p>&nbsp;<br \/>\n<strong>Larghezza:<\/strong> 24 cm | <strong>Altezza:<\/strong> 14 cm | <strong>Profondit\u00e0:<\/strong> 14 cm | <strong>Peso:<\/strong> 0,4 kg<\/p>\n","protected":false},"featured_media":189984,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1324],"product_tag":[1356],"class_list":{"0":"post-189983","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessori-da-viaggio","7":"product_tag-valentine","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beauty Case Vernazza \u2013 100% Made in Italy - Pelletterie D&amp;D<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pelletterieded.com\/it\/shop\/borse-da-viaggio\/accessori-da-viaggio\/beauty-case-vernazza-100-made-in-italy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beauty Case Vernazza \u2013 100% Made in Italy - Pelletterie D&amp;D\" \/>\n<meta property=\"og:description\" content=\"Realizzato artigianalmente in vero cuoio toscano, il beauty case Vernazza racchiude l\u2019essenza dell\u2019eccellenza italiana. I riflessi multicolore, ispirati al fascino della costa, restano impressi per sempre nel cuoio. Ideale per tenere in ordine i tuoi oggetti personali con stile, anche in viaggio.   &nbsp; Larghezza: 24 cm | Altezza: 14 cm | Profondit\u00e0: 14 cm | Peso: 0,4 kg\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pelletterieded.com\/it\/shop\/borse-da-viaggio\/accessori-da-viaggio\/beauty-case-vernazza-100-made-in-italy\/\" \/>\n<meta property=\"og:site_name\" content=\"Pelletterie D&amp;D\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dedpelletterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T07:29:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2025\/07\/1-scaled-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/borse-da-viaggio\\\/accessori-da-viaggio\\\/beauty-case-vernazza-100-made-in-italy\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/borse-da-viaggio\\\/accessori-da-viaggio\\\/beauty-case-vernazza-100-made-in-italy\\\/\",\"name\":\"Beauty Case Vernazza \u2013 100% Made in Italy - Pelletterie D&amp;D\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/borse-da-viaggio\\\/accessori-da-viaggio\\\/beauty-case-vernazza-100-made-in-italy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/borse-da-viaggio\\\/accessori-da-viaggio\\\/beauty-case-vernazza-100-made-in-italy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/1-scaled-scaled.webp\",\"datePublished\":\"2025-07-30T06:33:09+00:00\",\"dateModified\":\"2026-02-10T07:29:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/borse-da-viaggio\\\/accessori-da-viaggio\\\/beauty-case-vernazza-100-made-in-italy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/borse-da-viaggio\\\/accessori-da-viaggio\\\/beauty-case-vernazza-100-made-in-italy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/borse-da-viaggio\\\/accessori-da-viaggio\\\/beauty-case-vernazza-100-made-in-italy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/1-scaled-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/1-scaled-scaled.webp\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/borse-da-viaggio\\\/accessori-da-viaggio\\\/beauty-case-vernazza-100-made-in-italy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pelletterie D&amp;D\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"shop\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Borse da viaggio\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/borse-da-viaggio\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Accessori da viaggio\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/borse-da-viaggio\\\/accessori-da-viaggio\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Beauty Case Vernazza \u2013 100% Made in Italy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/\",\"name\":\"Pelletterie D&D\",\"description\":\"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#organization\",\"name\":\"Pelletterie D&D\",\"alternateName\":\"D&D Pelletterie\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"width\":185,\"height\":200,\"caption\":\"Pelletterie D&D\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dedpelletterie\",\"https:\\\/\\\/www.instagram.com\\\/pelletterieded\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beauty Case Vernazza \u2013 100% Made in Italy - Pelletterie D&amp;D","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pelletterieded.com\/it\/shop\/borse-da-viaggio\/accessori-da-viaggio\/beauty-case-vernazza-100-made-in-italy\/","og_locale":"it_IT","og_type":"article","og_title":"Beauty Case Vernazza \u2013 100% Made in Italy - Pelletterie D&amp;D","og_description":"Realizzato artigianalmente in vero cuoio toscano, il beauty case Vernazza racchiude l\u2019essenza dell\u2019eccellenza italiana. I riflessi multicolore, ispirati al fascino della costa, restano impressi per sempre nel cuoio. Ideale per tenere in ordine i tuoi oggetti personali con stile, anche in viaggio.   &nbsp; Larghezza: 24 cm | Altezza: 14 cm | Profondit\u00e0: 14 cm | Peso: 0,4 kg","og_url":"https:\/\/pelletterieded.com\/it\/shop\/borse-da-viaggio\/accessori-da-viaggio\/beauty-case-vernazza-100-made-in-italy\/","og_site_name":"Pelletterie D&amp;D","article_publisher":"https:\/\/www.facebook.com\/dedpelletterie","article_modified_time":"2026-02-10T07:29:31+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2025\/07\/1-scaled-scaled.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pelletterieded.com\/it\/shop\/borse-da-viaggio\/accessori-da-viaggio\/beauty-case-vernazza-100-made-in-italy\/","url":"https:\/\/pelletterieded.com\/it\/shop\/borse-da-viaggio\/accessori-da-viaggio\/beauty-case-vernazza-100-made-in-italy\/","name":"Beauty Case Vernazza \u2013 100% Made in Italy - Pelletterie D&amp;D","isPartOf":{"@id":"https:\/\/pelletterieded.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pelletterieded.com\/it\/shop\/borse-da-viaggio\/accessori-da-viaggio\/beauty-case-vernazza-100-made-in-italy\/#primaryimage"},"image":{"@id":"https:\/\/pelletterieded.com\/it\/shop\/borse-da-viaggio\/accessori-da-viaggio\/beauty-case-vernazza-100-made-in-italy\/#primaryimage"},"thumbnailUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2025\/07\/1-scaled-scaled.webp","datePublished":"2025-07-30T06:33:09+00:00","dateModified":"2026-02-10T07:29:31+00:00","breadcrumb":{"@id":"https:\/\/pelletterieded.com\/it\/shop\/borse-da-viaggio\/accessori-da-viaggio\/beauty-case-vernazza-100-made-in-italy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pelletterieded.com\/it\/shop\/borse-da-viaggio\/accessori-da-viaggio\/beauty-case-vernazza-100-made-in-italy\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/pelletterieded.com\/it\/shop\/borse-da-viaggio\/accessori-da-viaggio\/beauty-case-vernazza-100-made-in-italy\/#primaryimage","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2025\/07\/1-scaled-scaled.webp","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2025\/07\/1-scaled-scaled.webp","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/pelletterieded.com\/it\/shop\/borse-da-viaggio\/accessori-da-viaggio\/beauty-case-vernazza-100-made-in-italy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pelletterie D&amp;D","item":"https:\/\/pelletterieded.com\/it\/"},{"@type":"ListItem","position":2,"name":"shop","item":"https:\/\/pelletterieded.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Borse da viaggio","item":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/borse-da-viaggio\/"},{"@type":"ListItem","position":4,"name":"Accessori da viaggio","item":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/borse-da-viaggio\/accessori-da-viaggio\/"},{"@type":"ListItem","position":5,"name":"Beauty Case Vernazza \u2013 100% Made in Italy"}]},{"@type":"WebSite","@id":"https:\/\/pelletterieded.com\/it\/#website","url":"https:\/\/pelletterieded.com\/it\/","name":"Pelletterie D&D","description":"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.","publisher":{"@id":"https:\/\/pelletterieded.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pelletterieded.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/pelletterieded.com\/it\/#organization","name":"Pelletterie D&D","alternateName":"D&D Pelletterie","url":"https:\/\/pelletterieded.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/pelletterieded.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","width":185,"height":200,"caption":"Pelletterie D&D"},"image":{"@id":"https:\/\/pelletterieded.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dedpelletterie","https:\/\/www.instagram.com\/pelletterieded\/"]}]}},"_links":{"self":[{"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product\/189983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/comments?post=189983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/media\/189984"}],"wp:attachment":[{"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/media?parent=189983"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product_brand?post=189983"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product_cat?post=189983"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product_tag?post=189983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}