{"id":126452,"date":"2019-10-20T13:47:14","date_gmt":"2019-10-20T11:47:14","guid":{"rendered":"http:\/\/pelletterieded.com\/?post_type=product&#038;p=126452"},"modified":"2025-07-27T15:40:38","modified_gmt":"2025-07-27T13:40:38","slug":"marsupio-classic-grande","status":"publish","type":"product","link":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/marsupi\/marsupio-classic-grande\/","title":{"rendered":"Marsupio Classic Grande"},"content":{"rendered":"<p>Realizzata completamente in Italia da abili pellettieri mediante l\u2019utilizzo di un pellame bovino conciato con tannini vegetali e successivamente tamponato a mano.<\/p>\n<p>La caratteristica di questo pellame naturale offre una piacevolezza al tatto e uno stile inconfondibile della pelletteria italiana.<\/p>\n<p>La vendita dell\u2019oggetto viene gestita direttamente dall\u2019azienda che lo produce<\/p>\n<p><strong>ESTERNI:<\/strong><\/p>\n<p>\u2013 pelle pieno fiore conciata la vegetale e tamponata a mano<\/p>\n<p>\u2013 costruzione semi morbida<\/p>\n<p>\u2013 chiusura con zip<\/p>\n<p>\u2013 tracolla in pelle regolabile<\/p>\n<p>\u2013 tasca posteriore con chiusura a zip<\/p>\n<p>\u2013 quattro tasche frontali con chiusura a zip<\/p>\n<p>\u2013 accessori in metallo<\/p>\n<p><strong>INTERNI:<\/strong><\/p>\n<p>&#8211; rivestimento interno in tessuto<\/p>\n<p>&#8211; una tasca con chiusura a zip<\/p>\n<p><strong>ACCESSORI:<\/strong><\/p>\n<p>\u2013 accessori in ottone spazzolato (sulle varianti colore marroni)<\/p>\n<p>\u2013 accessori palladio (sulle varianti colore rosso e nero)<\/p>\n<p><strong>DIMENSIONI:<\/strong><\/p>\n<p>Larghezza: 37cm | Altezza: 14cm | Profondit\u00e0: 8cm | Peso: 0,6kg<\/p>\n<p>Lunghezza con cintura: 125cm<\/p>\n<p><strong>CUSTODIA PROTETTIVA<\/strong>: sacchetto anti polvere incluso.<\/p>\n<p><strong>GARANZIA<\/strong>: 24 mesi.<\/p>\n<p><strong>CODICE INTERNO:<\/strong> 0606B.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Marsupio artigianale<\/strong>\u00a0100% Made in Italy realizzato in\u00a0<strong>vero cuoio\u00a0<\/strong>Toscano, con tracolla in pelle e tre tasche davanti e una dietro con chiusura a zip.<br \/>\nPerfetto e sicuro per viaggiare in comodit\u00e0.<br \/>\nPerfetto anche come regalo<\/p>\n<p><strong>Larghezza:<\/strong> 37cm | <strong>Altezza:<\/strong> 14cm | <strong>Profondit\u00e0:<\/strong> 8cm | <strong>Peso<\/strong>: 0,6kg<\/p>\n","protected":false},"featured_media":165393,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1318,1366,899,348,330],"product_tag":[],"class_list":["post-126452","product","type-product","status-publish","has-post-thumbnail","product_cat-saldi-20","product_cat-best-seller","product_cat-borse-bicolore-uomo-donna-uniche-originali","product_cat-marsupi","product_cat-borse-da-viaggio","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes","wvs-archive-product-wrapper"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marsupio Classic Grande - Pelletterie D&amp;D<\/title>\n<meta name=\"description\" content=\"Marsupio artigianale\u00a0100% Made in Italy realizzato in\u00a0vero cuoio\u00a0Toscano, con tracolla in pelle e tre tasche davanti e una dietro con chiusura a zip.Perfetto e sicuro per viaggiare in comodit\u00e0.Perfetto anche come regalo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pelletterieded.com\/it\/shop\/uomo\/marsupi\/marsupio-classic-grande\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marsupio Classic Grande - Pelletterie D&amp;D\" \/>\n<meta property=\"og:description\" content=\"Marsupio artigianale\u00a0100% Made in Italy realizzato in\u00a0vero cuoio\u00a0Toscano, con tracolla in pelle e tre tasche davanti e una dietro con chiusura a zip.Perfetto e sicuro per viaggiare in comodit\u00e0.Perfetto anche come regalo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pelletterieded.com\/it\/shop\/uomo\/marsupi\/marsupio-classic-grande\/\" \/>\n<meta property=\"og:site_name\" content=\"Pelletterie D&amp;D\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dedpelletterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-27T13:40:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0606B-multicolore-jpg.avif\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/marsupi\\\/marsupio-classic-grande\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/marsupi\\\/marsupio-classic-grande\\\/\",\"name\":\"Marsupio Classic Grande - Pelletterie D&amp;D\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/marsupi\\\/marsupio-classic-grande\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/marsupi\\\/marsupio-classic-grande\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/0606B-multicolore-jpg.avif\",\"datePublished\":\"2019-10-20T11:47:14+00:00\",\"dateModified\":\"2025-07-27T13:40:38+00:00\",\"description\":\"Marsupio artigianale\u00a0100% Made in Italy realizzato in\u00a0vero cuoio\u00a0Toscano, con tracolla in pelle e tre tasche davanti e una dietro con chiusura a zip.Perfetto e sicuro per viaggiare in comodit\u00e0.Perfetto anche come regalo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/marsupi\\\/marsupio-classic-grande\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/marsupi\\\/marsupio-classic-grande\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/marsupi\\\/marsupio-classic-grande\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/0606B-multicolore-jpg.avif\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/0606B-multicolore-jpg.avif\",\"width\":1100,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/uomo\\\/marsupi\\\/marsupio-classic-grande\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pelletterie D&amp;D\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"shop\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Uomo\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/uomo\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Marsupi\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/uomo\\\/marsupi\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Marsupio Classic Grande\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/\",\"name\":\"Pelletterie D&D\",\"description\":\"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"LocalBusiness\",\"OnlineStore\"],\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#organization\",\"name\":\"Pelletterie D&D\",\"alternateName\":[\"D&D Pelletterie\",\"Pelletterie D e D\",\"Pelletterie DED\"],\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"width\":185,\"height\":200,\"caption\":\"Pelletterie D&D\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dedpelletterie\",\"https:\\\/\\\/www.instagram.com\\\/pelletterieded\\\/\",\"https:\\\/\\\/www.feedaty.com\\\/recensioni\\\/pelletterieded\",\"https:\\\/\\\/www.amazon.it\\\/stores\\\/page\\\/EEBC9051-1D83-453F-A8AE-7FE798E14B5A\"],\"legalName\":\"Pelletterie D & D S.r.l.\",\"vatID\":\"IT06541790488\",\"taxID\":\"06541790488\",\"description\":\"Pelletteria artigianale toscana nata come laboratorio negli anni '90. Specializzata in borse da medico in vera pelle conciata al vegetale, lavorata secondo la tradizione del distretto conciario di Santa Croce sull'Arno. Fondata sul principio \\\"Artigianato, non moda\\\".\",\"slogan\":\"Borse che custodiscono il tempo\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Via Renato Bruschi 138\",\"addressLocality\":\"Sesto Fiorentino\",\"addressRegion\":\"FI\",\"postalCode\":\"50019\",\"addressCountry\":\"IT\"},\"foundingLocation\":{\"@type\":\"Place\",\"name\":\"Santa Croce sull'Arno, Toscana, Italia\",\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Santa Croce sull'Arno\",\"addressRegion\":\"Toscana\",\"addressCountry\":\"IT\"}},\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"+39 055 4491006\",\"email\":\"info@pelletterieded.com\",\"contactType\":\"customer service\",\"availableLanguage\":[\"Italian\",\"English\",\"Spanish\",\"French\",\"German\"]},\"areaServed\":[{\"@type\":\"Country\",\"name\":\"Italy\"},{\"@type\":\"Place\",\"name\":\"European Union\"}],\"knowsAbout\":[\"Borse da medico in pelle\",\"Doctor bags made in Italy\",\"Tuscan vegetable-tanned leather\",\"Italian artisanal leather goods\",\"Personalized leather bags\",\"Hot-stamping leather personalization\",\"Made in Italy leather craftsmanship\",\"Briefcases for professionals\"],\"hasCredential\":{\"@type\":\"EducationalOccupationalCredential\",\"name\":\"Consorzio Vera Pelle Italiana Conciata al Vegetale\",\"description\":\"Leather sourced from tanneries that are members of the Italian Vegetable-Tanned Genuine Leather Consortium\"},\"makesOffer\":[{\"@type\":\"OfferCatalog\",\"name\":\"Pelletterie D&D leather goods\",\"itemListElement\":[{\"@type\":\"OfferCatalog\",\"name\":\"Borse da medico in pelle\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/borse-da-medico\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Borse donna in pelle toscana\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/donna\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Borse uomo in pelle professionale\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/uomo\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Borse da viaggio in pelle italiana\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/borse-da-viaggio\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Piccola pelletteria italiana\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/extra\\\/\"}]}],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"applicableCountry\":\"IT\",\"returnPolicyCategory\":\"https:\\\/\\\/schema.org\\\/MerchantReturnFiniteReturnWindow\",\"merchantReturnDays\":14}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marsupio Classic Grande - Pelletterie D&amp;D","description":"Marsupio artigianale\u00a0100% Made in Italy realizzato in\u00a0vero cuoio\u00a0Toscano, con tracolla in pelle e tre tasche davanti e una dietro con chiusura a zip.Perfetto e sicuro per viaggiare in comodit\u00e0.Perfetto anche come regalo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/marsupi\/marsupio-classic-grande\/","og_locale":"it_IT","og_type":"article","og_title":"Marsupio Classic Grande - Pelletterie D&amp;D","og_description":"Marsupio artigianale\u00a0100% Made in Italy realizzato in\u00a0vero cuoio\u00a0Toscano, con tracolla in pelle e tre tasche davanti e una dietro con chiusura a zip.Perfetto e sicuro per viaggiare in comodit\u00e0.Perfetto anche come regalo","og_url":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/marsupi\/marsupio-classic-grande\/","og_site_name":"Pelletterie D&amp;D","article_publisher":"https:\/\/www.facebook.com\/dedpelletterie","article_modified_time":"2025-07-27T13:40:38+00:00","og_image":[{"width":1100,"height":1100,"url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0606B-multicolore-jpg.avif","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/marsupi\/marsupio-classic-grande\/","url":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/marsupi\/marsupio-classic-grande\/","name":"Marsupio Classic Grande - Pelletterie D&amp;D","isPartOf":{"@id":"https:\/\/pelletterieded.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/marsupi\/marsupio-classic-grande\/#primaryimage"},"image":{"@id":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/marsupi\/marsupio-classic-grande\/#primaryimage"},"thumbnailUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0606B-multicolore-jpg.avif","datePublished":"2019-10-20T11:47:14+00:00","dateModified":"2025-07-27T13:40:38+00:00","description":"Marsupio artigianale\u00a0100% Made in Italy realizzato in\u00a0vero cuoio\u00a0Toscano, con tracolla in pelle e tre tasche davanti e una dietro con chiusura a zip.Perfetto e sicuro per viaggiare in comodit\u00e0.Perfetto anche come regalo","breadcrumb":{"@id":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/marsupi\/marsupio-classic-grande\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pelletterieded.com\/it\/shop\/uomo\/marsupi\/marsupio-classic-grande\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/marsupi\/marsupio-classic-grande\/#primaryimage","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0606B-multicolore-jpg.avif","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0606B-multicolore-jpg.avif","width":1100,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/pelletterieded.com\/it\/shop\/uomo\/marsupi\/marsupio-classic-grande\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pelletterie D&amp;D","item":"https:\/\/pelletterieded.com\/it\/"},{"@type":"ListItem","position":2,"name":"shop","item":"https:\/\/pelletterieded.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Uomo","item":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/uomo\/"},{"@type":"ListItem","position":4,"name":"Marsupi","item":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/uomo\/marsupi\/"},{"@type":"ListItem","position":5,"name":"Marsupio Classic Grande"}]},{"@type":"WebSite","@id":"https:\/\/pelletterieded.com\/it\/#website","url":"https:\/\/pelletterieded.com\/it\/","name":"Pelletterie D&D","description":"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.","publisher":{"@id":"https:\/\/pelletterieded.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pelletterieded.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","LocalBusiness","OnlineStore"],"@id":"https:\/\/pelletterieded.com\/it\/#organization","name":"Pelletterie D&D","alternateName":["D&D Pelletterie","Pelletterie D e D","Pelletterie DED"],"url":"https:\/\/pelletterieded.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/pelletterieded.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","width":185,"height":200,"caption":"Pelletterie D&D"},"image":{"@id":"https:\/\/pelletterieded.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dedpelletterie","https:\/\/www.instagram.com\/pelletterieded\/","https:\/\/www.feedaty.com\/recensioni\/pelletterieded","https:\/\/www.amazon.it\/stores\/page\/EEBC9051-1D83-453F-A8AE-7FE798E14B5A"],"legalName":"Pelletterie D & D S.r.l.","vatID":"IT06541790488","taxID":"06541790488","description":"Pelletteria artigianale toscana nata come laboratorio negli anni '90. Specializzata in borse da medico in vera pelle conciata al vegetale, lavorata secondo la tradizione del distretto conciario di Santa Croce sull'Arno. Fondata sul principio \"Artigianato, non moda\".","slogan":"Borse che custodiscono il tempo","address":{"@type":"PostalAddress","streetAddress":"Via Renato Bruschi 138","addressLocality":"Sesto Fiorentino","addressRegion":"FI","postalCode":"50019","addressCountry":"IT"},"foundingLocation":{"@type":"Place","name":"Santa Croce sull'Arno, Toscana, Italia","address":{"@type":"PostalAddress","addressLocality":"Santa Croce sull'Arno","addressRegion":"Toscana","addressCountry":"IT"}},"contactPoint":{"@type":"ContactPoint","telephone":"+39 055 4491006","email":"info@pelletterieded.com","contactType":"customer service","availableLanguage":["Italian","English","Spanish","French","German"]},"areaServed":[{"@type":"Country","name":"Italy"},{"@type":"Place","name":"European Union"}],"knowsAbout":["Borse da medico in pelle","Doctor bags made in Italy","Tuscan vegetable-tanned leather","Italian artisanal leather goods","Personalized leather bags","Hot-stamping leather personalization","Made in Italy leather craftsmanship","Briefcases for professionals"],"hasCredential":{"@type":"EducationalOccupationalCredential","name":"Consorzio Vera Pelle Italiana Conciata al Vegetale","description":"Leather sourced from tanneries that are members of the Italian Vegetable-Tanned Genuine Leather Consortium"},"makesOffer":[{"@type":"OfferCatalog","name":"Pelletterie D&D leather goods","itemListElement":[{"@type":"OfferCatalog","name":"Borse da medico in pelle","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/borse-da-medico\/"},{"@type":"OfferCatalog","name":"Borse donna in pelle toscana","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/donna\/"},{"@type":"OfferCatalog","name":"Borse uomo in pelle professionale","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/uomo\/"},{"@type":"OfferCatalog","name":"Borse da viaggio in pelle italiana","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/borse-da-viaggio\/"},{"@type":"OfferCatalog","name":"Piccola pelletteria italiana","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/extra\/"}]}],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","applicableCountry":"IT","returnPolicyCategory":"https:\/\/schema.org\/MerchantReturnFiniteReturnWindow","merchantReturnDays":14}}]}},"_links":{"self":[{"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product\/126452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/comments?post=126452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/media\/165393"}],"wp:attachment":[{"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/media?parent=126452"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product_brand?post=126452"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product_cat?post=126452"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pelletterieded.com\/it\/wp-json\/wp\/v2\/product_tag?post=126452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}