{"id":599,"count":9,"description":"","link":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/herrentaschen\/schultertaschen-herrentaschen\/","name":"SCHULTERTASCHEN","slug":"schultertaschen-herrentaschen","taxonomy":"product_cat","parent":590,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SCHULTERTASCHEN - Pelletterie D&amp;D<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/herrentaschen\/schultertaschen-herrentaschen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SCHULTERTASCHEN - Pelletterie D&amp;D\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/herrentaschen\/schultertaschen-herrentaschen\/\" \/>\n<meta property=\"og:site_name\" content=\"Pelletterie D&amp;D\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/categoria-prodotto\\\/herrentaschen\\\/schultertaschen-herrentaschen\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/categoria-prodotto\\\/herrentaschen\\\/schultertaschen-herrentaschen\\\/\",\"name\":\"SCHULTERTASCHEN - Pelletterie D&amp;D\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/categoria-prodotto\\\/herrentaschen\\\/schultertaschen-herrentaschen\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/categoria-prodotto\\\/herrentaschen\\\/schultertaschen-herrentaschen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pelletterie D&amp;D\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einkaufen\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MANN\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/categoria-prodotto\\\/herrentaschen\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"SCHULTERTASCHEN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/\",\"name\":\"Pelletterie D&D\",\"description\":\"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#organization\",\"name\":\"Pelletterie D&D\",\"alternateName\":\"D&D Pelletterie\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"width\":185,\"height\":200,\"caption\":\"Pelletterie D&D\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dedpelletterie\",\"https:\\\/\\\/www.instagram.com\\\/pelletterieded\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SCHULTERTASCHEN - Pelletterie D&amp;D","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/herrentaschen\/schultertaschen-herrentaschen\/","og_locale":"de_DE","og_type":"article","og_title":"SCHULTERTASCHEN - Pelletterie D&amp;D","og_url":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/herrentaschen\/schultertaschen-herrentaschen\/","og_site_name":"Pelletterie D&amp;D","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/herrentaschen\/schultertaschen-herrentaschen\/","url":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/herrentaschen\/schultertaschen-herrentaschen\/","name":"SCHULTERTASCHEN - Pelletterie D&amp;D","isPartOf":{"@id":"https:\/\/pelletterieded.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/herrentaschen\/schultertaschen-herrentaschen\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/herrentaschen\/schultertaschen-herrentaschen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pelletterie D&amp;D","item":"https:\/\/pelletterieded.com\/de\/"},{"@type":"ListItem","position":2,"name":"Einkaufen","item":"https:\/\/pelletterieded.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"MANN","item":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/herrentaschen\/"},{"@type":"ListItem","position":4,"name":"SCHULTERTASCHEN"}]},{"@type":"WebSite","@id":"https:\/\/pelletterieded.com\/de\/#website","url":"https:\/\/pelletterieded.com\/de\/","name":"Pelletterie D&D","description":"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.","publisher":{"@id":"https:\/\/pelletterieded.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pelletterieded.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/pelletterieded.com\/de\/#organization","name":"Pelletterie D&D","alternateName":"D&D Pelletterie","url":"https:\/\/pelletterieded.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pelletterieded.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","width":185,"height":200,"caption":"Pelletterie D&D"},"image":{"@id":"https:\/\/pelletterieded.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dedpelletterie","https:\/\/www.instagram.com\/pelletterieded\/"]}]}},"_links":{"self":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_cat\/599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_cat\/590"}],"wp:post_type":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product?product_cat=599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}