{"id":126198,"date":"2020-10-16T13:56:41","date_gmt":"2020-10-16T11:56:45","guid":{"rendered":"http:\/\/pelletterieded.com\/?post_type=product&#038;p=126198"},"modified":"2025-07-27T15:45:43","modified_gmt":"2025-07-27T13:45:43","slug":"minimal-zweifarbigem-arzttasche-mit-instrumenten-fach","status":"publish","type":"product","link":"https:\/\/pelletterieded.com\/de\/shop\/arzttaschen\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\/","title":{"rendered":"Minimal zweifarbigem Arzttasche mit Instrumenten fach"},"content":{"rendered":"<p>Vollst\u00e4ndig in Italien von Lederfacharbeitern hergestellt, unter Verwendung eines mit pflanzlichen Gerbstoffen gegerbten und anschlie\u00dfend von Hand gepufferten Rindsleders.<\/p>\n<p>Die Charakteristik dieses Naturleders bietet einen angenehmen Griff und einen unverwechselbaren Stil italienischer Lederwaren.<\/p>\n<p>Der Verkauf des Objekts wird direkt von dem Unternehmen verwaltet, das es herstellt.<\/p>\n<p><strong>\u00c4u\u00dferes:<\/strong><\/p>\n<p>\u2013 pflanzlich gegerbtes vollnarbiges und von Hand gepuffertes Leder<\/p>\n<p>\u2013 \u00a0halbweiche Konstruktion<\/p>\n<p>\u2013 \u00a0schnappschnallen-Verschluss (Schl\u00fcssel inbegriffen)<\/p>\n<p>\u2013 hintertasche mit Rei\u00dfverschluss<\/p>\n<p>\u2013 handgriff aus Leder<\/p>\n<p>\u2013 hintere Trolley-Schlaufe<\/p>\n<p>\u2013 instrumentenfach mit Reissverschluss und doppeltem Rei\u00dfverschlusszug<\/p>\n<p>\u2013 abnehmbarer und verstellbarer Schulterriemen aus Leder<\/p>\n<p>\u2013 metallzubeh\u00f6r<\/p>\n<p>\u2013 metallf\u00fc\u00dfe<\/p>\n<p><strong>Inneres:<\/strong><\/p>\n<p>\u2013 stofffutter<\/p>\n<p>\u2013 zwei Abteile<\/p>\n<p>\u2013 trennwand mit Rei\u00dfverschluss<\/p>\n<p>\u2013 tasche f\u00fcr IPad\/Dokumentenhalter<\/p>\n<p>\u2013 eine Rei\u00dfverschlusstasche mit Revers aus Leder<\/p>\n<p>\u2013 zubeh\u00f6r aus Metall<\/p>\n<p><strong>Zubeh\u00f6r:<\/strong><\/p>\n<p>\u2013 zubeh\u00f6r aus geschliffenem Messing (bei den braunen Farbvarianten)<\/p>\n<p>\u2013 zubeh\u00f6r aus Palladium (bei roten und schwarzen Farbvarianten)<\/p>\n<p><strong>Abmessungen:<\/strong><\/p>\n<p>Breite: 35.5m | H\u00f6he: 24cm | Tiefe: 17cm |<\/p>\n<p><strong>Schutzh\u00fclle<\/strong>: einschlie\u00dflich Staubschutzbeutel.<\/p>\n<p><strong>Garantie<\/strong>: 24 Monate<\/p>\n<p><strong>Interner Kodex<\/strong>: 0208<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Breite<\/strong>: 35.5m | <strong>H\u00f6he<\/strong>: 24cm | <strong>Tiefe<\/strong>: 17cm |<\/p>\n","protected":false},"featured_media":126389,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[903,524],"product_tag":[],"class_list":{"0":"post-126198","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zweifarbig","7":"product_cat-arzttaschen","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-variable","14":"has-default-attributes","15":"wvs-archive-product-wrapper"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Minimal zweifarbigem Arzttasche mit Instrumenten fach - Pelletterie D&amp;D<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pelletterieded.com\/de\/shop\/arzttaschen\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minimal zweifarbigem Arzttasche mit Instrumenten fach - Pelletterie D&amp;D\" \/>\n<meta property=\"og:description\" content=\"Breite: 35.5m | H\u00f6he: 24cm | Tiefe: 17cm |\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pelletterieded.com\/de\/shop\/arzttaschen\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\/\" \/>\n<meta property=\"og:site_name\" content=\"Pelletterie D&amp;D\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dedpelletterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-27T13:45:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2020\/10\/0208-7-jpg.avif\" \/>\n\t<meta property=\"og:image:width\" content=\"1831\" \/>\n\t<meta property=\"og:image:height\" content=\"1658\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/arzttaschen\\\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/arzttaschen\\\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\\\/\",\"name\":\"Minimal zweifarbigem Arzttasche mit Instrumenten fach - Pelletterie D&amp;D\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/arzttaschen\\\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/arzttaschen\\\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/0208-7-jpg.avif\",\"datePublished\":\"2020-10-16T11:56:45+00:00\",\"dateModified\":\"2025-07-27T13:45:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/arzttaschen\\\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/arzttaschen\\\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/arzttaschen\\\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/0208-7-jpg.avif\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/0208-7-jpg.avif\",\"width\":1831,\"height\":1658},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/arzttaschen\\\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pelletterie D&amp;D\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einkaufen\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arzttaschen\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/categoria-prodotto\\\/arzttaschen\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Minimal zweifarbigem Arzttasche mit Instrumenten fach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/\",\"name\":\"Pelletterie D&D\",\"description\":\"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#organization\",\"name\":\"Pelletterie D&D\",\"alternateName\":\"D&D Pelletterie\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"width\":185,\"height\":200,\"caption\":\"Pelletterie D&D\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dedpelletterie\",\"https:\\\/\\\/www.instagram.com\\\/pelletterieded\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Minimal zweifarbigem Arzttasche mit Instrumenten fach - Pelletterie D&amp;D","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pelletterieded.com\/de\/shop\/arzttaschen\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\/","og_locale":"de_DE","og_type":"article","og_title":"Minimal zweifarbigem Arzttasche mit Instrumenten fach - Pelletterie D&amp;D","og_description":"Breite: 35.5m | H\u00f6he: 24cm | Tiefe: 17cm |","og_url":"https:\/\/pelletterieded.com\/de\/shop\/arzttaschen\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\/","og_site_name":"Pelletterie D&amp;D","article_publisher":"https:\/\/www.facebook.com\/dedpelletterie","article_modified_time":"2025-07-27T13:45:43+00:00","og_image":[{"width":1831,"height":1658,"url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2020\/10\/0208-7-jpg.avif","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pelletterieded.com\/de\/shop\/arzttaschen\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\/","url":"https:\/\/pelletterieded.com\/de\/shop\/arzttaschen\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\/","name":"Minimal zweifarbigem Arzttasche mit Instrumenten fach - Pelletterie D&amp;D","isPartOf":{"@id":"https:\/\/pelletterieded.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pelletterieded.com\/de\/shop\/arzttaschen\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\/#primaryimage"},"image":{"@id":"https:\/\/pelletterieded.com\/de\/shop\/arzttaschen\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\/#primaryimage"},"thumbnailUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2020\/10\/0208-7-jpg.avif","datePublished":"2020-10-16T11:56:45+00:00","dateModified":"2025-07-27T13:45:43+00:00","breadcrumb":{"@id":"https:\/\/pelletterieded.com\/de\/shop\/arzttaschen\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pelletterieded.com\/de\/shop\/arzttaschen\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pelletterieded.com\/de\/shop\/arzttaschen\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\/#primaryimage","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2020\/10\/0208-7-jpg.avif","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2020\/10\/0208-7-jpg.avif","width":1831,"height":1658},{"@type":"BreadcrumbList","@id":"https:\/\/pelletterieded.com\/de\/shop\/arzttaschen\/minimal-zweifarbigem-arzttasche-mit-instrumenten-fach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pelletterie D&amp;D","item":"https:\/\/pelletterieded.com\/de\/"},{"@type":"ListItem","position":2,"name":"Einkaufen","item":"https:\/\/pelletterieded.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Arzttaschen","item":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/arzttaschen\/"},{"@type":"ListItem","position":4,"name":"Minimal zweifarbigem Arzttasche mit Instrumenten fach"}]},{"@type":"WebSite","@id":"https:\/\/pelletterieded.com\/de\/#website","url":"https:\/\/pelletterieded.com\/de\/","name":"Pelletterie D&D","description":"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.","publisher":{"@id":"https:\/\/pelletterieded.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pelletterieded.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/pelletterieded.com\/de\/#organization","name":"Pelletterie D&D","alternateName":"D&D Pelletterie","url":"https:\/\/pelletterieded.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pelletterieded.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","width":185,"height":200,"caption":"Pelletterie D&D"},"image":{"@id":"https:\/\/pelletterieded.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dedpelletterie","https:\/\/www.instagram.com\/pelletterieded\/"]}]}},"_links":{"self":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product\/126198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/comments?post=126198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/media\/126389"}],"wp:attachment":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/media?parent=126198"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_brand?post=126198"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_cat?post=126198"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_tag?post=126198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}