{"id":109851,"date":"2018-07-25T13:37:28","date_gmt":"2018-07-25T11:37:28","guid":{"rendered":"http:\/\/pelletterieded.com\/cartella-messenger\/"},"modified":"2025-07-27T15:45:42","modified_gmt":"2025-07-27T13:45:42","slug":"messenger-ordner","status":"publish","type":"product","link":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/business-de\/messenger-ordner\/","title":{"rendered":"Messenger-Ordner"},"content":{"rendered":"<p>Vollst\u00e4ndig in Italien von Lederfacharbeitern hergestellt, unter Verwendung eines mit pflanzlichen Gerbstoffen gegerbten und anschlie\u00dfend von Hand gepufferten Rindsleders.<\/p>\n<p>Die Charakteristik dieses Naturleders bietet einen angenehmen Griff und einen unverwechselbaren Stil italienischer Lederwaren.<\/p>\n<p>Der Verkauf des Objekts wird direkt von dem Unternehmen verwaltet, das es herstellt.<\/p>\n<p><strong>\u00c4u\u00dferes:<\/strong><\/p>\n<p>\u2013 pflanzlich gegerbtes vollnarbiges und von Hand gepuffertes Leder<\/p>\n<p>\u2013 halbweiche Konstruktion<\/p>\n<p>\u2013 doppeltes Tuc-Schlo\u00df (Drucktastenverschluss) (Schl\u00fcssel inbegriffen)<\/p>\n<p>\u2013 handgriff aus Leder<\/p>\n<p>\u2013 zwei Vordertaschen<\/p>\n<p>\u2013 vordertasche mit Rei\u00dfverschluss<\/p>\n<p>\u2013 r\u00fcckseitige Tasche mit Rei\u00dfverschluss<\/p>\n<p>\u2013 abnehmbarer und verstellbarer Schulterriemen aus Leder<\/p>\n<p>\u2013 metallzubeh\u00f6r<\/p>\n<p><strong>Inneres:<\/strong><\/p>\n<p>\u2013stofffutter<\/p>\n<p>\u2013 zwei Abteile<\/p>\n<p>\u2013 tasche mit Rei\u00dfverschluss und Lederrevers<\/p>\n<p>\u2013 Pc-Tasche<\/p>\n<p>\u2013 zwei nebeneinanderliegende Taschen f\u00fcr Gegenst\u00e4nde<\/p>\n<p>\u2013 ledertaschen f\u00fcr Karten und Stifte<\/p>\n<p>\u2013 zubeh\u00f6r aus Metall<\/p>\n<p><strong>Zubeh\u00f6r:<\/strong><\/p>\n<p>\u2013 Zubeh\u00f6r aus geschliffenem Messing (bei den braunen Farbvarianten)<\/p>\n<p>\u2013 Zubeh\u00f6r aus Palladium (bei roten und schwarzen Farbvarianten)<\/p>\n<p><strong>Abmessungen:<\/strong><\/p>\n<p>Breite: 42cm | H\u00f6he: 28cm | Tiefe: 12cm<\/p>\n<p><strong>Schutzh\u00fclle<\/strong>: einschlie\u00dflich Staubschutzbeutel.<\/p>\n<p><strong>Garantie<\/strong>: 24 Monate<\/p>\n<p><strong>Interner Kodex<\/strong>: 0706.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Breite<\/strong>: 42cm | <strong>H\u00f6he<\/strong>: 28cm | <strong>Tiefe<\/strong>: 12cm<\/p>\n","protected":false},"featured_media":124406,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[547,509,554],"product_tag":[],"class_list":{"0":"post-109851","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-aktentasche","7":"product_cat-business-de","8":"product_cat-pc-tasche","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-variable","15":"has-default-attributes","16":"wvs-archive-product-wrapper"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Messenger-Ordner - Pelletterie D&amp;D<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/business-de\/messenger-ordner\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Messenger-Ordner - Pelletterie D&amp;D\" \/>\n<meta property=\"og:description\" content=\"Breite: 42cm | H\u00f6he: 28cm | Tiefe: 12cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/business-de\/messenger-ordner\/\" \/>\n<meta property=\"og:site_name\" content=\"Pelletterie D&amp;D\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dedpelletterie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-27T13:45:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0706-marrone-scaled-jpg.avif\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/business-de\\\/messenger-ordner\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/business-de\\\/messenger-ordner\\\/\",\"name\":\"Messenger-Ordner - Pelletterie D&amp;D\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/business-de\\\/messenger-ordner\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/business-de\\\/messenger-ordner\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/0706-marrone-scaled-jpg.avif\",\"datePublished\":\"2018-07-25T11:37:28+00:00\",\"dateModified\":\"2025-07-27T13:45:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/business-de\\\/messenger-ordner\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/business-de\\\/messenger-ordner\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/business-de\\\/messenger-ordner\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/0706-marrone-scaled-jpg.avif\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/0706-marrone-scaled-jpg.avif\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/business-de\\\/messenger-ordner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pelletterie D&amp;D\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einkaufen\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MANN\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/categoria-prodotto\\\/herrentaschen\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Business\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/categoria-prodotto\\\/herrentaschen\\\/business-de\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Messenger-Ordner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/\",\"name\":\"Pelletterie D&D\",\"description\":\"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#organization\",\"name\":\"Pelletterie D&D\",\"alternateName\":\"D&D Pelletterie\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"width\":185,\"height\":200,\"caption\":\"Pelletterie D&D\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dedpelletterie\",\"https:\\\/\\\/www.instagram.com\\\/pelletterieded\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Messenger-Ordner - Pelletterie D&amp;D","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/business-de\/messenger-ordner\/","og_locale":"de_DE","og_type":"article","og_title":"Messenger-Ordner - Pelletterie D&amp;D","og_description":"Breite: 42cm | H\u00f6he: 28cm | Tiefe: 12cm","og_url":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/business-de\/messenger-ordner\/","og_site_name":"Pelletterie D&amp;D","article_publisher":"https:\/\/www.facebook.com\/dedpelletterie","article_modified_time":"2025-07-27T13:45:42+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0706-marrone-scaled-jpg.avif","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/business-de\/messenger-ordner\/","url":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/business-de\/messenger-ordner\/","name":"Messenger-Ordner - Pelletterie D&amp;D","isPartOf":{"@id":"https:\/\/pelletterieded.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/business-de\/messenger-ordner\/#primaryimage"},"image":{"@id":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/business-de\/messenger-ordner\/#primaryimage"},"thumbnailUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0706-marrone-scaled-jpg.avif","datePublished":"2018-07-25T11:37:28+00:00","dateModified":"2025-07-27T13:45:42+00:00","breadcrumb":{"@id":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/business-de\/messenger-ordner\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/business-de\/messenger-ordner\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/business-de\/messenger-ordner\/#primaryimage","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0706-marrone-scaled-jpg.avif","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0706-marrone-scaled-jpg.avif","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/business-de\/messenger-ordner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pelletterie D&amp;D","item":"https:\/\/pelletterieded.com\/de\/"},{"@type":"ListItem","position":2,"name":"Einkaufen","item":"https:\/\/pelletterieded.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"MANN","item":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/herrentaschen\/"},{"@type":"ListItem","position":4,"name":"Business","item":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/herrentaschen\/business-de\/"},{"@type":"ListItem","position":5,"name":"Messenger-Ordner"}]},{"@type":"WebSite","@id":"https:\/\/pelletterieded.com\/de\/#website","url":"https:\/\/pelletterieded.com\/de\/","name":"Pelletterie D&D","description":"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.","publisher":{"@id":"https:\/\/pelletterieded.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pelletterieded.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/pelletterieded.com\/de\/#organization","name":"Pelletterie D&D","alternateName":"D&D Pelletterie","url":"https:\/\/pelletterieded.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pelletterieded.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","width":185,"height":200,"caption":"Pelletterie D&D"},"image":{"@id":"https:\/\/pelletterieded.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dedpelletterie","https:\/\/www.instagram.com\/pelletterieded\/"]}]}},"_links":{"self":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product\/109851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/comments?post=109851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/media\/124406"}],"wp:attachment":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/media?parent=109851"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_brand?post=109851"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_cat?post=109851"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_tag?post=109851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}