{"id":109442,"date":"2018-07-30T15:34:21","date_gmt":"2018-07-30T13:34:21","guid":{"rendered":"http:\/\/pelletterieded.com\/hobo-bag\/"},"modified":"2026-07-23T10:13:29","modified_gmt":"2026-07-23T08:13:29","slug":"hobo-bag","status":"publish","type":"product","link":"https:\/\/pelletterieded.com\/de\/shop\/damentaschen\/schultertaschen-damentaschen\/hobo-bag\/","title":{"rendered":"Hobo Bag"},"content":{"rendered":"<p>Vollst\u00e4ndig in Italien von Lederfacharbeitern hergestellt, unter Verwendung eines mit pflanzlichen Gerbstoffen gegerbten und anschlie\u00dfend von Hand gepufferten Rindsleders.<\/p>\n<p>Die Charakteristik dieses Naturleders bietet einen angenehmen Griff und einen unverwechselbaren Stil italienischer Lederwaren.<\/p>\n<p>Der Verkauf des Objekts wird direkt von dem Unternehmen verwaltet, das es herstellt.<\/p>\n<p><strong>\u00c4u\u00dferes:<\/strong><\/p>\n<p>\u2013 pflanzlich gegerbtes vollnarbiges und von Hand gepuffertes Leder<\/p>\n<p>\u2013 halbweiche Konstruktion<\/p>\n<p>\u2013 rei\u00dfverschluss<\/p>\n<p>\u2013 verstellbarer Ledergriff, der in einen Schulterriemen umgewandelt werden kann<\/p>\n<p>\u2013 metallzubeh\u00f6r<\/p>\n<p><strong>Inneres:<\/strong><\/p>\n<p>\u2013 stofffutter<\/p>\n<p>\u2013 zwei Abteile<\/p>\n<p>\u2013 trennwand mit Rei\u00dfverschluss<\/p>\n<p>\u2013 zwei nebeneinanderliegende Taschen f\u00fcr Handy\u00a0 oder Dokumente<\/p>\n<p>\u2013 zubeh\u00f6r aus Metall<\/p>\n<p><strong>Zubeh\u00f6r:<\/strong><\/p>\n<p>\u2013 Zubeh\u00f6r aus geschliffenem Messing (bei den braunen Farbvarianten)<\/p>\n<p>\u2013 Zubeh\u00f6r aus Palladium (bei roten und schwarzen Farbvarianten)<\/p>\n<p><strong>Abmessungen:<\/strong><\/p>\n<p>Breite: 36cm | H\u00f6he: 32cm | Tiefe: 14cm | Gewicht: 0,850kg<\/p>\n<p>L\u00e4nge Schultergurt: 95cm<\/p>\n<p><strong>Schutzh\u00fclle<\/strong>: einschlie\u00dflich Staubschutzbeutel.<\/p>\n<p><strong>Garantie<\/strong>: 24 Monate<\/p>\n<p><strong>Interner Kodex<\/strong>: 1218.<\/p>\n<p><!-- peld-seo-geo:start --><\/p>\n<h2>Material und Verarbeitung<\/h2>\n<p>Die Hobo Bag ist eine Hobo-Tasche f\u00fcr Damen aus toskanischem Leder, von erfahrenen T\u00e4schnern von Hand gefertigt. Das toskanische Leder ist pflanzlich gegerbt, aus Gerbereien des Consorzio Vera Pelle Italiana Conciata al Vegetale, und von Hand tamponiert; so entwickelt es mit der Zeit eine Patina, die seinen Gebrauch erz\u00e4hlt. Die Verarbeitung erfolgt zu 100 % Made in Italy im Ledermacher-Zentrum von Santa Croce sull&#8217;Arno, mit Beschl\u00e4gen aus geb\u00fcrstetem Messing bei den braunen Varianten und Palladium bei Rot und Schwarz sowie Rei\u00dfverschl\u00fcssen von YKK.<\/p>\n<h2>Ma\u00dfe und F\u00e4cher<\/h2>\n<p>Ma\u00dfe: Breite 36 \u00d7 H\u00f6he 32 \u00d7 Tiefe 14 cm.<\/p>\n<p>Halbweiche Konstruktion mit Rei\u00dfverschluss und einem verstellbaren Griff, der zu einem Schulterriemen von 95 cm wird. Das mit Stoff gef\u00fctterte Innere hat zwei F\u00e4cher, ein Zwischenfach mit Rei\u00dfverschluss und zwei F\u00e4cher f\u00fcr Handy oder Dokumente.<\/p>\n<h2>Kostenlose Personalisierung<\/h2>\n<p>Sie k\u00f6nnen die Tasche kostenlos per Hei\u00dfpr\u00e4gung personalisieren: Initialen oder vollst\u00e4ndiger Name, direkt bei der Bestellung angegeben, ohne Aufpreis.<\/p>\n<h2>Versand und Garantie<\/h2>\n<p>Jede Tasche ist durch eine Garantie von 24 Monaten abgedeckt und wird mit einem Staubbeutel geliefert. Der Versand ist in die gesamte Europ\u00e4ische Union m\u00f6glich.<\/p>\n<h2>H\u00e4ufige Fragen<\/h2>\n<details>\n<summary>Wie wird die Hobo Bag getragen?<\/summary>\n<p>Der Griff ist verstellbar und wird zu einem Schulterriemen von 95 cm; der Verschluss erfolgt \u00fcber einen Rei\u00dfverschluss.<\/p>\n<\/details>\n<details>\n<summary>Welche Ma\u00dfe hat die Hobo Bag?<\/summary>\n<p>Sie misst 36 cm in der Breite, 32 cm in der H\u00f6he und 14 cm in der Tiefe, mit zwei F\u00e4chern und einem Zwischenfach mit Rei\u00dfverschluss.<\/p>\n<\/details>\n<details>\n<summary>Wie viele Taschen hat sie im Inneren?<\/summary>\n<p>Das mit Stoff gef\u00fctterte Innere hat zwei F\u00e4cher, ein Zwischenfach mit Rei\u00dfverschluss und zwei F\u00e4cher f\u00fcr Handy oder Dokumente.<\/p>\n<\/details>\n<details>\n<summary>Kann ich die Tasche mit meinem Namen personalisieren?<\/summary>\n<p>Ja. Die Hei\u00dfpr\u00e4gung ist kostenlos: Sie k\u00f6nnen Initialen oder den vollst\u00e4ndigen Namen bei der Bestellung hinzuf\u00fcgen, ohne Aufpreis.<\/p>\n<\/details>\n<details>\n<summary>Aus welchem Leder ist sie gefertigt?<\/summary>\n<p>Es ist vollnarbiges toskanisches Leder, pflanzlich gegerbt, zertifiziert vom Consorzio Vera Pelle Italiana Conciata al Vegetale und von Hand tamponiert, zu 100 % Made in Italy.<\/p>\n<\/details>\n<p><script type=\"application\/ld+json\">{\"@context\": \"https:\/\/schema.org\", \"@type\": \"FAQPage\", \"mainEntity\": [{\"@type\": \"Question\", \"name\": \"Wie wird die Hobo Bag getragen?\", \"acceptedAnswer\": {\"@type\": \"Answer\", \"text\": \"Der Griff ist verstellbar und wird zu einem Schulterriemen von 95 cm; der Verschluss erfolgt \u00fcber einen Rei\u00dfverschluss.\"}}, {\"@type\": \"Question\", \"name\": \"Welche Ma\u00dfe hat die Hobo Bag?\", \"acceptedAnswer\": {\"@type\": \"Answer\", \"text\": \"Sie misst 36 cm in der Breite, 32 cm in der H\u00f6he und 14 cm in der Tiefe, mit zwei F\u00e4chern und einem Zwischenfach mit Rei\u00dfverschluss.\"}}, {\"@type\": \"Question\", \"name\": \"Wie viele Taschen hat sie im Inneren?\", \"acceptedAnswer\": {\"@type\": \"Answer\", \"text\": \"Das mit Stoff gef\u00fctterte Innere hat zwei F\u00e4cher, ein Zwischenfach mit Rei\u00dfverschluss und zwei F\u00e4cher f\u00fcr Handy oder Dokumente.\"}}, {\"@type\": \"Question\", \"name\": \"Kann ich die Tasche mit meinem Namen personalisieren?\", \"acceptedAnswer\": {\"@type\": \"Answer\", \"text\": \"Ja. Die Hei\u00dfpr\u00e4gung ist kostenlos: Sie k\u00f6nnen Initialen oder den vollst\u00e4ndigen Namen bei der Bestellung hinzuf\u00fcgen, ohne Aufpreis.\"}}, {\"@type\": \"Question\", \"name\": \"Aus welchem Leder ist sie gefertigt?\", \"acceptedAnswer\": {\"@type\": \"Answer\", \"text\": \"Es ist vollnarbiges toskanisches Leder, pflanzlich gegerbt, zertifiziert vom Consorzio Vera Pelle Italiana Conciata al Vegetale und von Hand tamponiert, zu 100 % Made in Italy.\"}}]}<\/script><br \/>\n<!-- peld-seo-geo:end --><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Breite<\/strong>: 36cm | <strong>H\u00f6he<\/strong>: 32cm | <strong>Tiefe<\/strong>: 14cm | <strong>Gewicht<\/strong>: 0,850kg<\/p>\n","protected":false},"featured_media":123672,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1658,559,1706,570],"product_tag":[],"class_list":["post-109442","product","type-product","status-publish","has-post-thumbnail","product_cat-best-seller-de","product_cat-damentaschen","product_cat-hobo-bag-de","product_cat-schultertaschen-damentaschen","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes","wvs-archive-product-wrapper"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hobo Bag: Ledertasche Damen | D&amp;D<\/title>\n<meta name=\"description\" content=\"Hobo-Tasche f\u00fcr Damen aus toskanischem Leder, Griff wird zum Riemen, pflanzlich gegerbt. Mit Hei\u00dfpr\u00e4gung personalisierbar. Varianten entdecken.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pelletterieded.com\/de\/shop\/damentaschen\/schultertaschen-damentaschen\/hobo-bag\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hobo Bag: Ledertasche Damen | D&amp;D\" \/>\n<meta property=\"og:description\" content=\"Hobo-Tasche f\u00fcr Damen aus toskanischem Leder, Griff wird zum Riemen, pflanzlich gegerbt. Mit Hei\u00dfpr\u00e4gung personalisierbar. Varianten entdecken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pelletterieded.com\/de\/shop\/damentaschen\/schultertaschen-damentaschen\/hobo-bag\/\" \/>\n<meta property=\"og:site_name\" content=\"Pelletterie D&amp;D\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dedpelletterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-23T08:13:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/1218-marrone-scaled-jpg.avif\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/damentaschen\\\/schultertaschen-damentaschen\\\/hobo-bag\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/damentaschen\\\/schultertaschen-damentaschen\\\/hobo-bag\\\/\",\"name\":\"Hobo Bag: Ledertasche Damen | D&D\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/damentaschen\\\/schultertaschen-damentaschen\\\/hobo-bag\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/damentaschen\\\/schultertaschen-damentaschen\\\/hobo-bag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/1218-marrone-scaled-jpg.avif\",\"datePublished\":\"2018-07-30T13:34:21+00:00\",\"dateModified\":\"2026-07-23T08:13:29+00:00\",\"description\":\"Hobo-Tasche f\u00fcr Damen aus toskanischem Leder, Griff wird zum Riemen, pflanzlich gegerbt. Mit Hei\u00dfpr\u00e4gung personalisierbar. Varianten entdecken.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/damentaschen\\\/schultertaschen-damentaschen\\\/hobo-bag\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/damentaschen\\\/schultertaschen-damentaschen\\\/hobo-bag\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/damentaschen\\\/schultertaschen-damentaschen\\\/hobo-bag\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/1218-marrone-scaled-jpg.avif\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/1218-marrone-scaled-jpg.avif\",\"width\":2560,\"height\":2560,\"caption\":\"Hobo Bag f\u00fcr Damen aus pflanzlich gegerbtem Toskana-Leder mit zum Riemen wandelbarem Griff, Made in Italy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/damentaschen\\\/schultertaschen-damentaschen\\\/hobo-bag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pelletterie D&amp;D\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/home-page-nuova-2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einkaufen\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Damentaschen\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/categoria-prodotto\\\/damentaschen\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Hobo-Taschen\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/categoria-prodotto\\\/damentaschen\\\/donna-hobo-bag-de\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Hobo Bag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/\",\"name\":\"Pelletterie D&D\",\"description\":\"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"LocalBusiness\",\"OnlineStore\"],\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/#organization\",\"name\":\"Pelletterie D&D\",\"alternateName\":[\"D&D Pelletterie\",\"Pelletterie D e D\",\"Pelletterie DED\"],\"url\":\"https:\\\/\\\/pelletterieded.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"width\":185,\"height\":200,\"caption\":\"Pelletterie D&D\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dedpelletterie\",\"https:\\\/\\\/www.instagram.com\\\/pelletterieded\\\/\",\"https:\\\/\\\/www.feedaty.com\\\/recensioni\\\/pelletterieded\",\"https:\\\/\\\/www.amazon.it\\\/stores\\\/page\\\/EEBC9051-1D83-453F-A8AE-7FE798E14B5A\"],\"legalName\":\"Pelletterie D & D S.r.l.\",\"vatID\":\"IT06541790488\",\"taxID\":\"06541790488\",\"description\":\"Pelletteria artigianale toscana nata come laboratorio negli anni '90. Specializzata in borse da medico in vera pelle conciata al vegetale, lavorata secondo la tradizione del distretto conciario di Santa Croce sull'Arno. Fondata sul principio \\\"Artigianato, non moda\\\".\",\"slogan\":\"Borse che custodiscono il tempo\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Via Renato Bruschi 138\",\"addressLocality\":\"Sesto Fiorentino\",\"addressRegion\":\"FI\",\"postalCode\":\"50019\",\"addressCountry\":\"IT\"},\"foundingLocation\":{\"@type\":\"Place\",\"name\":\"Santa Croce sull'Arno, Toscana, Italia\",\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Santa Croce sull'Arno\",\"addressRegion\":\"Toscana\",\"addressCountry\":\"IT\"}},\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"+39 055 4491006\",\"email\":\"info@pelletterieded.com\",\"contactType\":\"customer service\",\"availableLanguage\":[\"Italian\",\"English\",\"Spanish\",\"French\",\"German\"]},\"areaServed\":[{\"@type\":\"Country\",\"name\":\"Italy\"},{\"@type\":\"Place\",\"name\":\"European Union\"}],\"knowsAbout\":[\"Borse da medico in pelle\",\"Doctor bags made in Italy\",\"Tuscan vegetable-tanned leather\",\"Italian artisanal leather goods\",\"Personalized leather bags\",\"Hot-stamping leather personalization\",\"Made in Italy leather craftsmanship\",\"Briefcases for professionals\"],\"hasCredential\":{\"@type\":\"EducationalOccupationalCredential\",\"name\":\"Consorzio Vera Pelle Italiana Conciata al Vegetale\",\"description\":\"Leather sourced from tanneries that are members of the Italian Vegetable-Tanned Genuine Leather Consortium\"},\"makesOffer\":[{\"@type\":\"OfferCatalog\",\"name\":\"Pelletterie D&D leather goods\",\"itemListElement\":[{\"@type\":\"OfferCatalog\",\"name\":\"Borse da medico in pelle\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/borse-da-medico\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Borse donna in pelle toscana\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/donna\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Borse uomo in pelle professionale\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/uomo\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Borse da viaggio in pelle italiana\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/borse-da-viaggio\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Piccola pelletteria italiana\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/extra\\\/\"}]}],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"applicableCountry\":\"IT\",\"returnPolicyCategory\":\"https:\\\/\\\/schema.org\\\/MerchantReturnFiniteReturnWindow\",\"merchantReturnDays\":14}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hobo Bag: Ledertasche Damen | D&D","description":"Hobo-Tasche f\u00fcr Damen aus toskanischem Leder, Griff wird zum Riemen, pflanzlich gegerbt. Mit Hei\u00dfpr\u00e4gung personalisierbar. Varianten entdecken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pelletterieded.com\/de\/shop\/damentaschen\/schultertaschen-damentaschen\/hobo-bag\/","og_locale":"de_DE","og_type":"article","og_title":"Hobo Bag: Ledertasche Damen | D&D","og_description":"Hobo-Tasche f\u00fcr Damen aus toskanischem Leder, Griff wird zum Riemen, pflanzlich gegerbt. Mit Hei\u00dfpr\u00e4gung personalisierbar. Varianten entdecken.","og_url":"https:\/\/pelletterieded.com\/de\/shop\/damentaschen\/schultertaschen-damentaschen\/hobo-bag\/","og_site_name":"Pelletterie D&amp;D","article_publisher":"https:\/\/www.facebook.com\/dedpelletterie","article_modified_time":"2026-07-23T08:13:29+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/1218-marrone-scaled-jpg.avif","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pelletterieded.com\/de\/shop\/damentaschen\/schultertaschen-damentaschen\/hobo-bag\/","url":"https:\/\/pelletterieded.com\/de\/shop\/damentaschen\/schultertaschen-damentaschen\/hobo-bag\/","name":"Hobo Bag: Ledertasche Damen | D&D","isPartOf":{"@id":"https:\/\/pelletterieded.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pelletterieded.com\/de\/shop\/damentaschen\/schultertaschen-damentaschen\/hobo-bag\/#primaryimage"},"image":{"@id":"https:\/\/pelletterieded.com\/de\/shop\/damentaschen\/schultertaschen-damentaschen\/hobo-bag\/#primaryimage"},"thumbnailUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/1218-marrone-scaled-jpg.avif","datePublished":"2018-07-30T13:34:21+00:00","dateModified":"2026-07-23T08:13:29+00:00","description":"Hobo-Tasche f\u00fcr Damen aus toskanischem Leder, Griff wird zum Riemen, pflanzlich gegerbt. Mit Hei\u00dfpr\u00e4gung personalisierbar. Varianten entdecken.","breadcrumb":{"@id":"https:\/\/pelletterieded.com\/de\/shop\/damentaschen\/schultertaschen-damentaschen\/hobo-bag\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pelletterieded.com\/de\/shop\/damentaschen\/schultertaschen-damentaschen\/hobo-bag\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pelletterieded.com\/de\/shop\/damentaschen\/schultertaschen-damentaschen\/hobo-bag\/#primaryimage","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/1218-marrone-scaled-jpg.avif","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/1218-marrone-scaled-jpg.avif","width":2560,"height":2560,"caption":"Hobo Bag f\u00fcr Damen aus pflanzlich gegerbtem Toskana-Leder mit zum Riemen wandelbarem Griff, Made in Italy"},{"@type":"BreadcrumbList","@id":"https:\/\/pelletterieded.com\/de\/shop\/damentaschen\/schultertaschen-damentaschen\/hobo-bag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pelletterie D&amp;D","item":"https:\/\/pelletterieded.com\/de\/home-page-nuova-2021\/"},{"@type":"ListItem","position":2,"name":"Einkaufen","item":"https:\/\/pelletterieded.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Damentaschen","item":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/damentaschen\/"},{"@type":"ListItem","position":4,"name":"Hobo-Taschen","item":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/damentaschen\/donna-hobo-bag-de\/"},{"@type":"ListItem","position":5,"name":"Hobo Bag"}]},{"@type":"WebSite","@id":"https:\/\/pelletterieded.com\/de\/#website","url":"https:\/\/pelletterieded.com\/de\/","name":"Pelletterie D&D","description":"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.","publisher":{"@id":"https:\/\/pelletterieded.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pelletterieded.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","LocalBusiness","OnlineStore"],"@id":"https:\/\/pelletterieded.com\/#organization","name":"Pelletterie D&D","alternateName":["D&D Pelletterie","Pelletterie D e D","Pelletterie DED"],"url":"https:\/\/pelletterieded.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pelletterieded.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","width":185,"height":200,"caption":"Pelletterie D&D"},"image":{"@id":"https:\/\/pelletterieded.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dedpelletterie","https:\/\/www.instagram.com\/pelletterieded\/","https:\/\/www.feedaty.com\/recensioni\/pelletterieded","https:\/\/www.amazon.it\/stores\/page\/EEBC9051-1D83-453F-A8AE-7FE798E14B5A"],"legalName":"Pelletterie D & D S.r.l.","vatID":"IT06541790488","taxID":"06541790488","description":"Pelletteria artigianale toscana nata come laboratorio negli anni '90. Specializzata in borse da medico in vera pelle conciata al vegetale, lavorata secondo la tradizione del distretto conciario di Santa Croce sull'Arno. Fondata sul principio \"Artigianato, non moda\".","slogan":"Borse che custodiscono il tempo","address":{"@type":"PostalAddress","streetAddress":"Via Renato Bruschi 138","addressLocality":"Sesto Fiorentino","addressRegion":"FI","postalCode":"50019","addressCountry":"IT"},"foundingLocation":{"@type":"Place","name":"Santa Croce sull'Arno, Toscana, Italia","address":{"@type":"PostalAddress","addressLocality":"Santa Croce sull'Arno","addressRegion":"Toscana","addressCountry":"IT"}},"contactPoint":{"@type":"ContactPoint","telephone":"+39 055 4491006","email":"info@pelletterieded.com","contactType":"customer service","availableLanguage":["Italian","English","Spanish","French","German"]},"areaServed":[{"@type":"Country","name":"Italy"},{"@type":"Place","name":"European Union"}],"knowsAbout":["Borse da medico in pelle","Doctor bags made in Italy","Tuscan vegetable-tanned leather","Italian artisanal leather goods","Personalized leather bags","Hot-stamping leather personalization","Made in Italy leather craftsmanship","Briefcases for professionals"],"hasCredential":{"@type":"EducationalOccupationalCredential","name":"Consorzio Vera Pelle Italiana Conciata al Vegetale","description":"Leather sourced from tanneries that are members of the Italian Vegetable-Tanned Genuine Leather Consortium"},"makesOffer":[{"@type":"OfferCatalog","name":"Pelletterie D&D leather goods","itemListElement":[{"@type":"OfferCatalog","name":"Borse da medico in pelle","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/borse-da-medico\/"},{"@type":"OfferCatalog","name":"Borse donna in pelle toscana","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/donna\/"},{"@type":"OfferCatalog","name":"Borse uomo in pelle professionale","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/uomo\/"},{"@type":"OfferCatalog","name":"Borse da viaggio in pelle italiana","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/borse-da-viaggio\/"},{"@type":"OfferCatalog","name":"Piccola pelletteria italiana","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/extra\/"}]}],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","applicableCountry":"IT","returnPolicyCategory":"https:\/\/schema.org\/MerchantReturnFiniteReturnWindow","merchantReturnDays":14}}]}},"_links":{"self":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product\/109442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/comments?post=109442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/media\/123672"}],"wp:attachment":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/media?parent=109442"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_brand?post=109442"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_cat?post=109442"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_tag?post=109442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}