{"id":108588,"date":"2018-07-12T16:30:09","date_gmt":"2018-07-12T15:30:09","guid":{"rendered":"http:\/\/pelletterieded.com\/borsa-porta-computer-minimal\/"},"modified":"2026-07-23T10:14:08","modified_gmt":"2026-07-23T08:14:08","slug":"minimal-computertasche","status":"publish","type":"product","link":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/uomo-business-de\/uomo-business-porta-pc-de\/minimal-computertasche\/","title":{"rendered":"Minimal Computertasche"},"content":{"rendered":"<p>Vollst\u00e4ndig in Italien von Lederfacharbeitern hergestellt, unter Verwendung eines mit pflanzlichen Gerbstoffen gegerbten und anschlie\u00dfend von Hand gepufferten Rindsleders.<\/p>\n<p>Die Charakteristik dieses Naturleders bietet einen angenehmen Griff und einen unverwechselbaren Stil italienischer Lederwaren.<\/p>\n<p>Der Verkauf des Objekts wird direkt von dem Unternehmen verwaltet, das es herstellt.<\/p>\n<p><strong>\u00c4u\u00dferes :<\/strong><\/p>\n<p>\u2013 pflanzlich gegerbtes vollnarbiges und von Hand gepuffertes Leder<\/p>\n<p>\u2013 halbstarre Konstruktion<\/p>\n<p>\u2013 reissverschluss mit doppeltem Rei\u00dfverschlusszug<\/p>\n<p>\u2013 handgriffe aus Leder<\/p>\n<p>\u2013 abnehmbarer und verstellbarer Schulterriemen aus Leder<\/p>\n<p>\u2013 metallzubeh\u00f6r<\/p>\n<p><strong>Inneres:<\/strong><\/p>\n<p>\u2013 stofffutter<\/p>\n<p>\u2013 zwei nebeneinanderliegende Taschen f\u00fcr Gegenst\u00e4nde<\/p>\n<p>\u2013 tasche mit Rei\u00dfverschluss und Lederrevers<\/p>\n<p>\u2013 zubeh\u00f6r aus Metall<\/p>\n<p><strong>Zubeh\u00f6r:<\/strong><\/p>\n<p>\u2013 Zubeh\u00f6r aus geschliffenem Messing (bei den braunen Farbvarianten)<\/p>\n<p>\u2013 Zubeh\u00f6r aus Palladium (bei roten und schwarzen Farbvarianten)<\/p>\n<p><strong>Abmessungen:<\/strong><\/p>\n<p>Breite: 36cm | H\u00f6he: 28cm | Tiefe: 7cm | Gewicht: 0,9kg<\/p>\n<p><strong>Schutzh\u00fclle<\/strong>: einschlie\u00dflich Staubschutzbeutel.<\/p>\n<p><strong>Garantie<\/strong>: 24 Monate<\/p>\n<p><strong>Interner Kodex<\/strong>: 0502.<\/p>\n<p><!-- peld-seo-geo:start --><\/p>\n<h2>Material und Verarbeitung<\/h2>\n<p>Die minimalistische Laptoptasche wird im Lederzentrum von Santa Croce sull&#8217;Arno in Handarbeit gefertigt, in weicher Bauweise. Das Leder ist toskanisches Vollnarbenleder, pflanzlich gegerbt, vom Consorzio Vera Pelle Italiana Conciata al Vegetale zertifiziert und von Hand veredelt, sodass es mit dem Gebrauch eine eigene Patina entwickelt. Die Beschl\u00e4ge bestehen aus geb\u00fcrstetem Messing bei den braunen Varianten und aus Palladium bei den roten und schwarzen Ausf\u00fchrungen, mit YKK-Rei\u00dfverschl\u00fcssen. Sie ist zu 100% Made in Italy.<\/p>\n<h2>Ma\u00dfe und F\u00e4cher<\/h2>\n<p>Ma\u00dfe: Breite 36 \u00d7 H\u00f6he 28 \u00d7 Tiefe 7 cm, Gewicht 0,5 kg.<\/p>\n<p>Die Bauweise ist weich, der Verschluss ein Rei\u00dfverschluss mit doppeltem Zipper. Der Innenraum ist mit Stoff gef\u00fcttert, mit zwei nebeneinanderliegenden Utensilientaschen und einer Rei\u00dfverschlusstasche mit Lederbesatz. Die Griffe sind aus Leder, der Schultergurt herausnehmbar und verstellbar.<\/p>\n<h2>Kostenlose Personalisierung<\/h2>\n<p>Jedes St\u00fcck l\u00e4sst sich mit Initialen oder Namen per Hei\u00dfpr\u00e4gung personalisieren, kostenlos im Preis enthalten: Geben Sie den gew\u00fcnschten Text einfach bei der Bestellung an.<\/p>\n<h2>Versand und Garantie<\/h2>\n<p>Versand in die gesamte Europ\u00e4ische Union und 24 Monate Garantie. Jedes fertige Produkt wird vor dem Versand von erfahrenen Lederfachleuten pers\u00f6nlich gepr\u00fcft und mit einem sch\u00fctzenden Staubbeutel geliefert.<\/p>\n<h2>H\u00e4ufige Fragen<\/h2>\n<details>\n<summary>Ist sie f\u00fcr einen Laptop geeignet?<\/summary>\n<p>Ja: Die Linie ist klar und weich, mit einem Hauptfach f\u00fcr einen schlanken Laptop und die t\u00e4glichen Dokumente.<\/p>\n<\/details>\n<details>\n<summary>Wie wird sie verschlossen?<\/summary>\n<p>Mit einem Rei\u00dfverschluss mit doppeltem Zipper, der das Hauptfach der Tasche m\u00fchelos \u00f6ffnet.<\/p>\n<\/details>\n<details>\n<summary>Hat sie einen Schultergurt?<\/summary>\n<p>Ja, der Ledergurt ist abnehmbar und verstellbar; alternativ tragen Sie sie an den Ledergriffen in der Hand.<\/p>\n<\/details>\n<details>\n<summary>Aus welchem Leder ist die Tasche gefertigt?<\/summary>\n<p>Toskanisches Vollnarbenleder, pflanzlich gegerbt, vom Consorzio Vera Pelle Italiana Conciata al Vegetale zertifiziert und von Hand veredelt. Die Beschl\u00e4ge bestehen aus geb\u00fcrstetem Messing oder Palladium; es ist vollst\u00e4ndig Made in Italy.<\/p>\n<\/details>\n<details>\n<summary>Kann ich die Tasche mit meinem Namen personalisieren?<\/summary>\n<p>Ja. Die Hei\u00dfpr\u00e4gung mit Initialen oder Namen ist kostenlos im Preis enthalten: Geben Sie sie einfach bei der Bestellung an. Der Versand erfolgt in die gesamte Europ\u00e4ische Union mit 24 Monaten Garantie.<\/p>\n<\/details>\n<p><script type=\"application\/ld+json\">{\"@context\": \"https:\/\/schema.org\", \"@type\": \"FAQPage\", \"mainEntity\": [{\"@type\": \"Question\", \"name\": \"Ist sie f\u00fcr einen Laptop geeignet?\", \"acceptedAnswer\": {\"@type\": \"Answer\", \"text\": \"Ja: Die Linie ist klar und weich, mit einem Hauptfach f\u00fcr einen schlanken Laptop und die t\u00e4glichen Dokumente.\"}}, {\"@type\": \"Question\", \"name\": \"Wie wird sie verschlossen?\", \"acceptedAnswer\": {\"@type\": \"Answer\", \"text\": \"Mit einem Rei\u00dfverschluss mit doppeltem Zipper, der das Hauptfach der Tasche m\u00fchelos \u00f6ffnet.\"}}, {\"@type\": \"Question\", \"name\": \"Hat sie einen Schultergurt?\", \"acceptedAnswer\": {\"@type\": \"Answer\", \"text\": \"Ja, der Ledergurt ist abnehmbar und verstellbar; alternativ tragen Sie sie an den Ledergriffen in der Hand.\"}}, {\"@type\": \"Question\", \"name\": \"Aus welchem Leder ist die Tasche gefertigt?\", \"acceptedAnswer\": {\"@type\": \"Answer\", \"text\": \"Toskanisches Vollnarbenleder, pflanzlich gegerbt, vom Consorzio Vera Pelle Italiana Conciata al Vegetale zertifiziert und von Hand veredelt. Die Beschl\u00e4ge bestehen aus geb\u00fcrstetem Messing oder Palladium; es ist vollst\u00e4ndig Made in Italy.\"}}, {\"@type\": \"Question\", \"name\": \"Kann ich die Tasche mit meinem Namen personalisieren?\", \"acceptedAnswer\": {\"@type\": \"Answer\", \"text\": \"Ja. Die Hei\u00dfpr\u00e4gung mit Initialen oder Namen ist kostenlos im Preis enthalten: Geben Sie sie einfach bei der Bestellung an. Der Versand erfolgt in die gesamte Europ\u00e4ische Union mit 24 Monaten Garantie.\"}}]}<\/script><br \/>\n<!-- peld-seo-geo:end --><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Breite<\/strong>: 36cm | <strong>H\u00f6he<\/strong>: 28cm | <strong>Tiefe<\/strong>: 7cm | <strong>Gewicht<\/strong>: 0,9kg<\/p>\n","protected":false},"featured_media":121462,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1658,509,1790,1833,590,554],"product_tag":[],"class_list":["post-108588","product","type-product","status-publish","has-post-thumbnail","product_cat-best-seller-de","product_cat-business-de","product_cat-uomo-business-de","product_cat-uomo-business-porta-pc-de","product_cat-herrentaschen","product_cat-pc-tasche","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes","wvs-archive-product-wrapper"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Minimalistische Laptoptasche aus Leder | D&amp;D<\/title>\n<meta name=\"description\" content=\"Weiche Laptoptasche aus toskanischem Leder mit klarer Linie. Herausnehmbarer Schultergurt und Innentaschen. Personalisierbar, Made in Italy, 24 Monate.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/uomo-business-de\/uomo-business-porta-pc-de\/minimal-computertasche\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minimalistische Laptoptasche aus Leder | D&amp;D\" \/>\n<meta property=\"og:description\" content=\"Weiche Laptoptasche aus toskanischem Leder mit klarer Linie. Herausnehmbarer Schultergurt und Innentaschen. Personalisierbar, Made in Italy, 24 Monate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/uomo-business-de\/uomo-business-porta-pc-de\/minimal-computertasche\/\" \/>\n<meta property=\"og:site_name\" content=\"Pelletterie D&amp;D\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dedpelletterie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-23T08:14:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0502-marrone-scaled-jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/uomo-business-de\\\/uomo-business-porta-pc-de\\\/minimal-computertasche\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/uomo-business-de\\\/uomo-business-porta-pc-de\\\/minimal-computertasche\\\/\",\"name\":\"Minimalistische Laptoptasche aus Leder | D&D\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/uomo-business-de\\\/uomo-business-porta-pc-de\\\/minimal-computertasche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/uomo-business-de\\\/uomo-business-porta-pc-de\\\/minimal-computertasche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/0502-marrone-scaled-jpg.webp\",\"datePublished\":\"2018-07-12T15:30:09+00:00\",\"dateModified\":\"2026-07-23T08:14:08+00:00\",\"description\":\"Weiche Laptoptasche aus toskanischem Leder mit klarer Linie. Herausnehmbarer Schultergurt und Innentaschen. Personalisierbar, Made in Italy, 24 Monate.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/uomo-business-de\\\/uomo-business-porta-pc-de\\\/minimal-computertasche\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/uomo-business-de\\\/uomo-business-porta-pc-de\\\/minimal-computertasche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/uomo-business-de\\\/uomo-business-porta-pc-de\\\/minimal-computertasche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/0502-marrone-scaled-jpg.webp\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/0502-marrone-scaled-jpg.webp\",\"width\":2560,\"height\":2560,\"caption\":\"Minimalistische weiche Laptoptasche aus toskanischem Leder mit Schultergurt, D&D\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/herrentaschen\\\/uomo-business-de\\\/uomo-business-porta-pc-de\\\/minimal-computertasche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pelletterie D&amp;D\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/home-page-nuova-2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einkaufen\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Business\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/categoria-prodotto\\\/business-de\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"PC TASCHE\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/categoria-prodotto\\\/business-de\\\/pc-tasche\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Minimal Computertasche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/\",\"name\":\"Pelletterie D&D\",\"description\":\"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"LocalBusiness\",\"OnlineStore\"],\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/#organization\",\"name\":\"Pelletterie D&D\",\"alternateName\":[\"D&D Pelletterie\",\"Pelletterie D e D\",\"Pelletterie DED\"],\"url\":\"https:\\\/\\\/pelletterieded.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"width\":185,\"height\":200,\"caption\":\"Pelletterie D&D\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dedpelletterie\",\"https:\\\/\\\/www.instagram.com\\\/pelletterieded\\\/\",\"https:\\\/\\\/www.feedaty.com\\\/recensioni\\\/pelletterieded\",\"https:\\\/\\\/www.amazon.it\\\/stores\\\/page\\\/EEBC9051-1D83-453F-A8AE-7FE798E14B5A\"],\"legalName\":\"Pelletterie D & D S.r.l.\",\"vatID\":\"IT06541790488\",\"taxID\":\"06541790488\",\"description\":\"Pelletteria artigianale toscana nata come laboratorio negli anni '90. Specializzata in borse da medico in vera pelle conciata al vegetale, lavorata secondo la tradizione del distretto conciario di Santa Croce sull'Arno. Fondata sul principio \\\"Artigianato, non moda\\\".\",\"slogan\":\"Borse che custodiscono il tempo\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Via Renato Bruschi 138\",\"addressLocality\":\"Sesto Fiorentino\",\"addressRegion\":\"FI\",\"postalCode\":\"50019\",\"addressCountry\":\"IT\"},\"foundingLocation\":{\"@type\":\"Place\",\"name\":\"Santa Croce sull'Arno, Toscana, Italia\",\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Santa Croce sull'Arno\",\"addressRegion\":\"Toscana\",\"addressCountry\":\"IT\"}},\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"+39 055 4491006\",\"email\":\"info@pelletterieded.com\",\"contactType\":\"customer service\",\"availableLanguage\":[\"Italian\",\"English\",\"Spanish\",\"French\",\"German\"]},\"areaServed\":[{\"@type\":\"Country\",\"name\":\"Italy\"},{\"@type\":\"Place\",\"name\":\"European Union\"}],\"knowsAbout\":[\"Borse da medico in pelle\",\"Doctor bags made in Italy\",\"Tuscan vegetable-tanned leather\",\"Italian artisanal leather goods\",\"Personalized leather bags\",\"Hot-stamping leather personalization\",\"Made in Italy leather craftsmanship\",\"Briefcases for professionals\"],\"hasCredential\":{\"@type\":\"EducationalOccupationalCredential\",\"name\":\"Consorzio Vera Pelle Italiana Conciata al Vegetale\",\"description\":\"Leather sourced from tanneries that are members of the Italian Vegetable-Tanned Genuine Leather Consortium\"},\"makesOffer\":[{\"@type\":\"OfferCatalog\",\"name\":\"Pelletterie D&D leather goods\",\"itemListElement\":[{\"@type\":\"OfferCatalog\",\"name\":\"Borse da medico in pelle\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/borse-da-medico\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Borse donna in pelle toscana\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/donna\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Borse uomo in pelle professionale\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/uomo\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Borse da viaggio in pelle italiana\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/borse-da-viaggio\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Piccola pelletteria italiana\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/extra\\\/\"}]}],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"applicableCountry\":\"IT\",\"returnPolicyCategory\":\"https:\\\/\\\/schema.org\\\/MerchantReturnFiniteReturnWindow\",\"merchantReturnDays\":14}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Minimalistische Laptoptasche aus Leder | D&D","description":"Weiche Laptoptasche aus toskanischem Leder mit klarer Linie. Herausnehmbarer Schultergurt und Innentaschen. Personalisierbar, Made in Italy, 24 Monate.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/uomo-business-de\/uomo-business-porta-pc-de\/minimal-computertasche\/","og_locale":"de_DE","og_type":"article","og_title":"Minimalistische Laptoptasche aus Leder | D&D","og_description":"Weiche Laptoptasche aus toskanischem Leder mit klarer Linie. Herausnehmbarer Schultergurt und Innentaschen. Personalisierbar, Made in Italy, 24 Monate.","og_url":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/uomo-business-de\/uomo-business-porta-pc-de\/minimal-computertasche\/","og_site_name":"Pelletterie D&amp;D","article_publisher":"https:\/\/www.facebook.com\/dedpelletterie","article_modified_time":"2026-07-23T08:14:08+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0502-marrone-scaled-jpg.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/uomo-business-de\/uomo-business-porta-pc-de\/minimal-computertasche\/","url":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/uomo-business-de\/uomo-business-porta-pc-de\/minimal-computertasche\/","name":"Minimalistische Laptoptasche aus Leder | D&D","isPartOf":{"@id":"https:\/\/pelletterieded.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/uomo-business-de\/uomo-business-porta-pc-de\/minimal-computertasche\/#primaryimage"},"image":{"@id":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/uomo-business-de\/uomo-business-porta-pc-de\/minimal-computertasche\/#primaryimage"},"thumbnailUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0502-marrone-scaled-jpg.webp","datePublished":"2018-07-12T15:30:09+00:00","dateModified":"2026-07-23T08:14:08+00:00","description":"Weiche Laptoptasche aus toskanischem Leder mit klarer Linie. Herausnehmbarer Schultergurt und Innentaschen. Personalisierbar, Made in Italy, 24 Monate.","breadcrumb":{"@id":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/uomo-business-de\/uomo-business-porta-pc-de\/minimal-computertasche\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/uomo-business-de\/uomo-business-porta-pc-de\/minimal-computertasche\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/uomo-business-de\/uomo-business-porta-pc-de\/minimal-computertasche\/#primaryimage","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0502-marrone-scaled-jpg.webp","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2018\/07\/0502-marrone-scaled-jpg.webp","width":2560,"height":2560,"caption":"Minimalistische weiche Laptoptasche aus toskanischem Leder mit Schultergurt, D&D"},{"@type":"BreadcrumbList","@id":"https:\/\/pelletterieded.com\/de\/shop\/herrentaschen\/uomo-business-de\/uomo-business-porta-pc-de\/minimal-computertasche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pelletterie D&amp;D","item":"https:\/\/pelletterieded.com\/de\/home-page-nuova-2021\/"},{"@type":"ListItem","position":2,"name":"Einkaufen","item":"https:\/\/pelletterieded.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Business","item":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/business-de\/"},{"@type":"ListItem","position":4,"name":"PC TASCHE","item":"https:\/\/pelletterieded.com\/de\/categoria-prodotto\/business-de\/pc-tasche\/"},{"@type":"ListItem","position":5,"name":"Minimal Computertasche"}]},{"@type":"WebSite","@id":"https:\/\/pelletterieded.com\/de\/#website","url":"https:\/\/pelletterieded.com\/de\/","name":"Pelletterie D&D","description":"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.","publisher":{"@id":"https:\/\/pelletterieded.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pelletterieded.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","LocalBusiness","OnlineStore"],"@id":"https:\/\/pelletterieded.com\/#organization","name":"Pelletterie D&D","alternateName":["D&D Pelletterie","Pelletterie D e D","Pelletterie DED"],"url":"https:\/\/pelletterieded.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pelletterieded.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","width":185,"height":200,"caption":"Pelletterie D&D"},"image":{"@id":"https:\/\/pelletterieded.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dedpelletterie","https:\/\/www.instagram.com\/pelletterieded\/","https:\/\/www.feedaty.com\/recensioni\/pelletterieded","https:\/\/www.amazon.it\/stores\/page\/EEBC9051-1D83-453F-A8AE-7FE798E14B5A"],"legalName":"Pelletterie D & D S.r.l.","vatID":"IT06541790488","taxID":"06541790488","description":"Pelletteria artigianale toscana nata come laboratorio negli anni '90. Specializzata in borse da medico in vera pelle conciata al vegetale, lavorata secondo la tradizione del distretto conciario di Santa Croce sull'Arno. Fondata sul principio \"Artigianato, non moda\".","slogan":"Borse che custodiscono il tempo","address":{"@type":"PostalAddress","streetAddress":"Via Renato Bruschi 138","addressLocality":"Sesto Fiorentino","addressRegion":"FI","postalCode":"50019","addressCountry":"IT"},"foundingLocation":{"@type":"Place","name":"Santa Croce sull'Arno, Toscana, Italia","address":{"@type":"PostalAddress","addressLocality":"Santa Croce sull'Arno","addressRegion":"Toscana","addressCountry":"IT"}},"contactPoint":{"@type":"ContactPoint","telephone":"+39 055 4491006","email":"info@pelletterieded.com","contactType":"customer service","availableLanguage":["Italian","English","Spanish","French","German"]},"areaServed":[{"@type":"Country","name":"Italy"},{"@type":"Place","name":"European Union"}],"knowsAbout":["Borse da medico in pelle","Doctor bags made in Italy","Tuscan vegetable-tanned leather","Italian artisanal leather goods","Personalized leather bags","Hot-stamping leather personalization","Made in Italy leather craftsmanship","Briefcases for professionals"],"hasCredential":{"@type":"EducationalOccupationalCredential","name":"Consorzio Vera Pelle Italiana Conciata al Vegetale","description":"Leather sourced from tanneries that are members of the Italian Vegetable-Tanned Genuine Leather Consortium"},"makesOffer":[{"@type":"OfferCatalog","name":"Pelletterie D&D leather goods","itemListElement":[{"@type":"OfferCatalog","name":"Borse da medico in pelle","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/borse-da-medico\/"},{"@type":"OfferCatalog","name":"Borse donna in pelle toscana","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/donna\/"},{"@type":"OfferCatalog","name":"Borse uomo in pelle professionale","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/uomo\/"},{"@type":"OfferCatalog","name":"Borse da viaggio in pelle italiana","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/borse-da-viaggio\/"},{"@type":"OfferCatalog","name":"Piccola pelletteria italiana","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/extra\/"}]}],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","applicableCountry":"IT","returnPolicyCategory":"https:\/\/schema.org\/MerchantReturnFiniteReturnWindow","merchantReturnDays":14}}]}},"_links":{"self":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product\/108588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/comments?post=108588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/media\/121462"}],"wp:attachment":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/media?parent=108588"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_brand?post=108588"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_cat?post=108588"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/product_tag?post=108588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}