{"id":161933,"date":"2022-02-07T18:56:45","date_gmt":"2022-02-07T17:56:45","guid":{"rendered":"http:\/\/pelletterieded.com\/gallery-e-cosa-dicono-di-noi\/"},"modified":"2022-02-07T18:56:46","modified_gmt":"2022-02-07T17:56:46","slug":"gallery-e-cosa-dicono-di-noi","status":"publish","type":"page","link":"https:\/\/pelletterieded.com\/de\/gallery-e-cosa-dicono-di-noi\/","title":{"rendered":"Gallery e cosa dicono di noi"},"content":{"rendered":"\t<div id=\"gap-1393186857\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1393186857 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-collapse row-full-width\"  id=\"row-584512231\">\n\n\t<div id=\"col-883136456\" class=\"col small-12 large-12\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(236, 236, 236);\" >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" ><i class=\"icon-star\" aria-hidden=\"true\"><\/i>Taschen sind nicht nur Gegenst\u00e4nde, sondern haben ihre eigene Pers\u00f6nlichkeit, passen Sie Ihre an!<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\t<div id=\"text-1111611974\" class=\"text\">\n\t\t\n<div> <strong> Es ist m\u00f6glich, das gew\u00e4hlte Produkt durch ein \u201eHei\u00dfpr\u00e4gen\u201c direkt auf der Haut zu personalisieren. <\/strong> <br \/> Die gravierte Oberfl\u00e4che \u00e4ndert sich leicht im Farbton und wird dunkler und dunkler raffinierte Farbe. Der Service ist kostenlos, muss aber zum Zeitpunkt der Bestellung durch Ausf\u00fcllen des entsprechenden Feldes angefordert werden. <\/div>\n<div>Die Anpassung der Tasche wird originalgetreu durchgef\u00fchrt<\/div>\n<div> <\/div>\n<div style = \"font-size: 10px; text-align: right;\"> <em> * Bitte beachten Sie: Kundenspezifische Taschen sind nicht f\u00fcr R\u00fccksendungen vorgesehen. Die Garantie hingegen bleibt aktiv <\/em> <\/div>\n\t\t\n<style>\n#text-1111611974 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-883136456 > .col-inner {\n  padding: 40px 0px 40px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-584512231 > .col > .col-inner {\n  padding: 40px 80px 40px 80px;\n}\n<\/style>\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >Die Fotos unserer Kunden<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-5 medium-columns-3 small-columns-2\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1119-personalizzata.webp\" title=\"Borsa Genova personalizzata con incisione a caldo\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"276\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1119-personalizzata-600x276.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1119-personalizzata-600x276.jpg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1119-personalizzata-1200x553.jpg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1119-personalizzata-768x354.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1119-personalizzata-1000x461.jpg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1119-personalizzata.webp 1389w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa Genova personalizzata con incisione a caldo<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-14-at-15.08.22.webp\" title=\"Cartella da lavoro Bisaccia don incisione\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-14-at-15.08.22-600x450.jpeg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-14-at-15.08.22-600x450.jpeg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-14-at-15.08.22-1200x900.jpeg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-14-at-15.08.22-768x576.jpeg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-14-at-15.08.22-1536x1152.jpeg 1536w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-14-at-15.08.22-1000x750.jpeg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-14-at-15.08.22.webp 2000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Cartella da lavoro Bisaccia don incisione<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0405-personalizzata.webp\" title=\"Cartella Professionale Siena con incisione\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0405-personalizzata-600x450.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0405-personalizzata-600x450.jpg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0405-personalizzata-1200x900.jpg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0405-personalizzata-768x576.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0405-personalizzata-1536x1152.jpg 1536w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0405-personalizzata-1000x750.jpg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0405-personalizzata.webp 2000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Cartella Professionale Siena con incisione<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-01-at-15.56.48-1.webp\" title=\"Borsa da Lavoro Portadocumenti Doppia personalizzata\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"432\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-01-at-15.56.48-1-600x432.jpeg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-01-at-15.56.48-1-600x432.jpeg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-01-at-15.56.48-1-1200x864.jpeg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-01-at-15.56.48-1-768x553.jpeg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-01-at-15.56.48-1-1000x720.jpeg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-01-at-15.56.48-1.webp 1494w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa da Lavoro Portadocumenti Doppia personalizzata<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.13-2.webp\" title=\"Cartella Zaino personalizzata\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.13-2-600x450.jpeg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.13-2-600x450.jpeg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.13-2-1200x900.jpeg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.13-2-768x576.jpeg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.13-2-1536x1152.jpeg 1536w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.13-2-1000x750.jpeg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.13-2.webp 2000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Cartella Zaino personalizzata<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1240-personalizzata.webp\" title=\"Secchiello Genova rosso personalizzato\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1240-personalizzata-450x600.jpeg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1240-personalizzata-450x600.jpeg 450w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1240-personalizzata-900x1200.jpeg 900w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1240-personalizzata-768x1024.jpeg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1240-personalizzata-1152x1536.jpeg 1152w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1240-personalizzata-1000x1333.jpeg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/1240-personalizzata.webp 1200w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Secchiello Genova rosso personalizzato<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/104-personalizzata.webp\" title=\"Portafoglio in pelle personalizzato\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/104-personalizzata-600x450.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/104-personalizzata-600x450.jpg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/104-personalizzata-1200x900.jpg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/104-personalizzata-768x576.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/104-personalizzata-1536x1152.jpg 1536w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/104-personalizzata-1000x750.jpg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/104-personalizzata.webp 1600w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Portafoglio in pelle personalizzato<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0201-rossa.webp\" title=\"Borsa medico con vano porta strumenti personalizzata\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"599\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0201-rossa.webp\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa medico con vano porta strumenti personalizzata<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0204-personalizzata.webp\" title=\"borsa medico stile classica  con incisione a caldo\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0204-personalizzata-600x450.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0204-personalizzata-600x450.jpg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0204-personalizzata-1200x900.jpg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0204-personalizzata-768x576.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0204-personalizzata-1536x1152.jpg 1536w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0204-personalizzata-1000x750.jpg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0204-personalizzata.webp 2048w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>borsa medico stile classica  con incisione a caldo<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/2021-02-15.webp\" title=\"Borsa medico personalizzata\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"337\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/2021-02-15-600x337.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/2021-02-15-600x337.jpg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/2021-02-15-768x432.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/2021-02-15.webp 980w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa medico personalizzata<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909916139.webp\" title=\"Borsa Medico con iniziali incise a caldo\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909916139-600x450.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909916139-600x450.jpg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909916139-768x576.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909916139.webp 980w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa Medico con iniziali incise a caldo<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.07-2.webp\" title=\"Marsupio Classic con incisione a caldo\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.07-2-600x450.jpeg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.07-2-600x450.jpeg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.07-2-1200x900.jpeg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.07-2-768x576.jpeg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.07-2-1536x1152.jpeg 1536w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.07-2-1000x750.jpeg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.07-2.webp 2000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Marsupio Classic con incisione a caldo<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909578643.webp\" title=\"Marsupio con personalizzazione\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909578643-600x450.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909578643-600x450.jpg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909578643-768x576.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909578643.webp 980w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Marsupio con personalizzazione<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-28-at-16.55.33-1.webp\" title=\"Zaino multicolor con incisione\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-28-at-16.55.33-1-450x600.jpeg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-28-at-16.55.33-1-450x600.jpeg 450w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-28-at-16.55.33-1-900x1200.jpeg 900w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-28-at-16.55.33-1-768x1024.jpeg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-28-at-16.55.33-1-1152x1536.jpeg 1152w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-28-at-16.55.33-1-1000x1333.jpeg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-28-at-16.55.33-1-1200x1600.jpeg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-28-at-16.55.33-1.webp 1500w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Zaino multicolor con incisione<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.09-1.webp\" title=\"Zaino full Travel personalizzato\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.09-1-450x600.jpeg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.09-1-450x600.jpeg 450w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.09-1-900x1200.jpeg 900w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.09-1-768x1024.jpeg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.09-1-1152x1536.jpeg 1152w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.09-1-1000x1333.jpeg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.09-1-1200x1600.jpeg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.09-1.webp 1500w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Zaino full Travel personalizzato<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/2021.jpeg.webp\" title=\"Zaino in pelle con personlaizzazione\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"504\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/2021.jpeg-504x600.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/2021.jpeg-504x600.jpg 504w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/2021.jpeg-768x915.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/2021.jpeg.webp 980w\" sizes=\"(max-width: 504px) 100vw, 504px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Zaino in pelle con personlaizzazione<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0208-personalizzata.webp\" title=\"Borsa medico minimal con vanoBicolor personalizzata mogano opaco\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0208-personalizzata-450x600.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0208-personalizzata-450x600.jpg 450w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0208-personalizzata.webp 640w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa medico minimal con vanoBicolor personalizzata mogano opaco<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-06-at-15.45.45.webp\" title=\"Borsa medico minimal con vano portastrumenti personalizzata\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-06-at-15.45.45-600x450.jpeg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-06-at-15.45.45-600x450.jpeg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-06-at-15.45.45-1200x900.jpeg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-06-at-15.45.45-768x576.jpeg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-06-at-15.45.45-1536x1152.jpeg 1536w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-06-at-15.45.45-1000x750.jpeg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-06-at-15.45.45.webp 2000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa medico minimal con vano portastrumenti personalizzata<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1604916266297.webp\" title=\"Borsa a spalla con incisione iniziali\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1604916266297-450x600.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1604916266297-450x600.jpg 450w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1604916266297-900x1200.jpg 900w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1604916266297-768x1024.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1604916266297.webp 980w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa a spalla con incisione iniziali<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909632968.webp\" title=\"Zaino con personalizzazione\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909632968-450x600.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909632968-450x600.jpg 450w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909632968-900x1200.jpg 900w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909632968-768x1024.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909632968.webp 980w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Zaino con personalizzazione<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909916299.webp\" title=\"Zaino Old school con logo e incisione a caldo\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909916299-450x600.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909916299-450x600.jpg 450w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909916299-900x1200.jpg 900w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909916299-768x1024.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909916299-1152x1536.jpg 1152w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909916299-1000x1333.jpg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909916299.webp 1200w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Zaino Old school con logo e incisione a caldo<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.08-1.webp\" title=\"Borsa Torino bicolore personalizzata \">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.08-1-600x450.jpeg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.08-1-600x450.jpeg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.08-1-1200x900.jpeg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.08-1-768x576.jpeg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.08-1-1536x1152.jpeg 1536w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.08-1-1000x750.jpeg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-07-at-16.28.08-1.webp 2000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa Torino bicolore personalizzata <\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826230.webp\" title=\"Borsa personalizzata.\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826230-450x600.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826230-450x600.jpg 450w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826230-900x1200.jpg 900w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826230-768x1024.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826230.webp 980w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa personalizzata.<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611910068947.webp\" title=\"Zaino con personalizzazione\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611910068947-450x600.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611910068947-450x600.jpg 450w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611910068947.webp 735w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Zaino con personalizzazione<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_115126.webp\" title=\"Borsa donna con nome inciso a caldo\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_115126-600x450.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_115126-600x450.jpg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_115126-768x576.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_115126.webp 980w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa donna con nome inciso a caldo<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_115921.webp\" title=\"Borsa donna con nome inciso a caldo\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_115921-450x600.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_115921-450x600.jpg 450w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_115921-900x1200.jpg 900w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_115921-768x1024.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_115921.webp 980w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa donna con nome inciso a caldo<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_121146.webp\" title=\"Borsa personalizzata con iniziale\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_121146-450x600.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_121146-450x600.jpg 450w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200121_121146.webp 735w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa personalizzata con iniziale<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/1606400585216-scaled.webp\" title=\"Borsa medico minimal con incisione lunga\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/1606400585216-600x450.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/1606400585216-600x450.jpg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/1606400585216-1200x900.jpg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/1606400585216-768x576.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/1606400585216-1536x1152.jpg 1536w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/1606400585216-2048x1536.jpg 2048w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/1606400585216-1000x750.jpg 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa medico minimal con incisione lunga<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/20210310_144957-scaled.webp\" title=\"Borsa da Lavoro Piatta personalizzata con incisione\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/20210310_144957-600x450.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/20210310_144957-600x450.jpg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/20210310_144957-1200x900.jpg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/20210310_144957-768x576.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/20210310_144957-1536x1152.jpg 1536w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/20210310_144957-2048x1536.jpg 2048w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/03\/20210310_144957-1000x750.jpg 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa da Lavoro Piatta personalizzata con incisione<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909578758.webp\" title=\"Borsa medico color\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909578758-450x600.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909578758-450x600.jpg 450w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909578758-900x1200.jpg 900w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909578758-768x1024.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909578758.webp 980w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsa medico color<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-13-at-09.45.51-1.webp\" title=\"Porta documenti personalizzato\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-13-at-09.45.51-1-600x450.jpeg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-13-at-09.45.51-1-600x450.jpeg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-13-at-09.45.51-1-1200x900.jpeg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-13-at-09.45.51-1-768x576.jpeg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-13-at-09.45.51-1-1536x1152.jpeg 1536w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-13-at-09.45.51-1-1000x750.jpeg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-13-at-09.45.51-1.webp 2000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Porta documenti personalizzato<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826342.webp\" title=\"Cartella portadocumenti personalizzata\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"337\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826342-600x337.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826342-600x337.jpg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826342-768x432.jpg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826342.webp 980w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Cartella portadocumenti personalizzata<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909826273.webp\" title=\"Postino Relax con incisione a caldo\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"600\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909826273-284x600.jpg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909826273-284x600.jpg 284w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909826273-568x1200.jpg 568w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909826273-727x1536.jpg 727w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/04\/1611909826273.webp 757w\" sizes=\"(max-width: 284px) 100vw, 284px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Postino Relax con incisione a caldo<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0115-personalizzata.webp\" title=\"Borsone Viaggio in cerniera con incisione a caldo\">            <div class=\"box has-hover gallery-box box-shade dark\">\n              <div class=\"box-image image-cover\" style=\"padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0115-personalizzata-600x450.jpeg\" class=\"attachment-medium size-medium wvs-archive-product-image\" alt=\"\" ids=\"143909,140563,143937,140598,140568,143942,133603,143914,143919,130439,130272,140558,130202,140608,140583,130434,143924,140553,130187,130237,140593,140578,130247,130297,130307,130312,130322,133588,133613,130222,140603,130257,140613,143947\" style=\"shade\" lightbox_image_size=\"original\" columns=\"5\" image_height=\"100%\" text_size=\"xsmall\" text_bg=\"rgba(48, 48, 48, 0.558)\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0115-personalizzata-600x450.jpeg 600w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0115-personalizzata-1200x900.jpeg 1200w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0115-personalizzata-768x576.jpeg 768w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0115-personalizzata-1536x1152.jpeg 1536w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0115-personalizzata-1000x750.jpeg 1000w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/06\/0115-personalizzata.webp 2000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>                                                  <div class=\"shade\"><\/div>\n                                              <\/div>\n              <div class=\"box-text text-left is-xsmall\" style=\"background-color:rgba(48, 48, 48, 0.558);\">\n                 <p>Borsone Viaggio in cerniera con incisione a caldo<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >Was sie \u00fcber uns sagen<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<div class=\"row\"  id=\"row-455832211\">\n\n\t<div id=\"col-2112643508\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <div class=\"icon-box testimonial-box icon-box-center text-center\">\n                <div class=\"icon-box-img testimonial-image circle\" style=\"width: 200px\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826230-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail wvs-archive-product-image\" alt=\"\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826230-300x300.jpg 300w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/1611909826230-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>        <\/div>\n                <div class=\"icon-box-text p-last-0\">\n          <div class=\"star-rating\" role=\"img\" aria-label=\"Rated 5 out of 5\"><span style=\"width:100%\"><strong class=\"rating\"><\/strong><\/span><\/div>  \t\t\t\t<div class=\"testimonial-text line-height-small italic test_text first-reset last-reset is-italic\">\n            \n<p> Sehr sch\u00f6ne Tasche, entspricht meinen Erwartungen! <\/p>\n          <\/div>\n          <div class=\"testimonial-meta pt-half\">\n             <strong class=\"testimonial-name test_name\">da Feedaty<\/strong>\n                          <span class=\"testimonial-company test_company\"><\/span>\n          <\/div>\n        <\/div>\n  <\/div>\n\n  \n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1821758189\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <div class=\"icon-box testimonial-box icon-box-center text-center\">\n                <div class=\"icon-box-img testimonial-image circle\" style=\"width: 163px\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/20190103_151125-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail wvs-archive-product-image\" alt=\"\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/20190103_151125-300x300.jpg 300w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/20190103_151125-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>        <\/div>\n                <div class=\"icon-box-text p-last-0\">\n          <div class=\"star-rating\" role=\"img\" aria-label=\"Rated 5 out of 5\"><span style=\"width:100%\"><strong class=\"rating\"><\/strong><\/span><\/div>  \t\t\t\t<div class=\"testimonial-text line-height-small italic test_text first-reset last-reset is-italic\">\n            \n<div class = \"e-box h-p2 -stacked -radius-none\">\n<p class = \"t-body h-my1\"> Seite gut gemacht. Dies ist mein zweiter Kauf und ich bin sowohl mit den Produkten als auch mit dem Service zufrieden. <\/p>\n<\/div>\n          <\/div>\n          <div class=\"testimonial-meta pt-half\">\n             <strong class=\"testimonial-name test_name\">da Feedaty<\/strong>\n                          <span class=\"testimonial-company test_company\"><\/span>\n          <\/div>\n        <\/div>\n  <\/div>\n\n  \n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:0px;height:21px;\"><\/div><\/div>\n<a href=\"https:\/\/www.feedaty.com\/feedaty\/reviews\/pelletterieded\" target=\"_blank\" class=\"button primary\" rel=\"noopener\" style=\"border-radius:14px;\">\n\t\t<span>\u00dcBER WAS SIE \u00dcBER UNS SAGEN ...<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1231838973\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n  <div class=\"icon-box testimonial-box icon-box-center text-center\">\n                <div class=\"icon-box-img testimonial-image circle\" style=\"width: 183px\">\n              <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200616_155424-300x300.jpg\" class=\"attachment-thumbnail size-thumbnail wvs-archive-product-image\" alt=\"\" srcset=\"https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200616_155424-300x300.jpg 300w, https:\/\/pelletterieded.com\/wp-content\/uploads\/2021\/02\/IMG_20200616_155424-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>        <\/div>\n                <div class=\"icon-box-text p-last-0\">\n          <div class=\"star-rating\" role=\"img\" aria-label=\"Rated 5 out of 5\"><span style=\"width:100%\"><strong class=\"rating\"><\/strong><\/span><\/div>  \t\t\t\t<div class=\"testimonial-text line-height-small italic test_text first-reset last-reset is-italic\">\n            \n<p> Lederwaren mit hervorragenden Produkten, Qualit\u00e4tsleder, schneller Versand, wirklich au\u00dfergew\u00f6hnliche Preise. Sehr zu empfehlen <\/p>\n          <\/div>\n          <div class=\"testimonial-meta pt-half\">\n             <strong class=\"testimonial-name test_name\">da Feedaty<\/strong>\n                          <span class=\"testimonial-company test_company\"><\/span>\n          <\/div>\n        <\/div>\n  <\/div>\n\n  \n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":275,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-161933","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gallery e cosa dicono di noi - Pelletterie D&amp;D<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pelletterieded.com\/de\/gallery-e-cosa-dicono-di-noi\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gallery e cosa dicono di noi - Pelletterie D&amp;D\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pelletterieded.com\/de\/gallery-e-cosa-dicono-di-noi\/\" \/>\n<meta property=\"og:site_name\" content=\"Pelletterie D&amp;D\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dedpelletterie\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-07T17:56:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/gallery-e-cosa-dicono-di-noi\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/gallery-e-cosa-dicono-di-noi\\\/\",\"name\":\"Gallery e cosa dicono di noi - Pelletterie D&amp;D\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#website\"},\"datePublished\":\"2022-02-07T17:56:45+00:00\",\"dateModified\":\"2022-02-07T17:56:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/gallery-e-cosa-dicono-di-noi\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pelletterieded.com\\\/de\\\/gallery-e-cosa-dicono-di-noi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/gallery-e-cosa-dicono-di-noi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pelletterie D&amp;D\",\"item\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/home-page-nuova-2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gallery e cosa dicono di noi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/\",\"name\":\"Pelletterie D&D\",\"description\":\"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"LocalBusiness\",\"OnlineStore\"],\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#organization\",\"name\":\"Pelletterie D&D\",\"alternateName\":[\"D&D Pelletterie\",\"Pelletterie D e D\",\"Pelletterie DED\"],\"url\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"contentUrl\":\"https:\\\/\\\/pelletterieded.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-pelletterie-ded-mail.webp\",\"width\":185,\"height\":200,\"caption\":\"Pelletterie D&D\"},\"image\":{\"@id\":\"https:\\\/\\\/pelletterieded.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dedpelletterie\",\"https:\\\/\\\/www.instagram.com\\\/pelletterieded\\\/\",\"https:\\\/\\\/www.feedaty.com\\\/recensioni\\\/pelletterieded\",\"https:\\\/\\\/www.amazon.it\\\/stores\\\/page\\\/EEBC9051-1D83-453F-A8AE-7FE798E14B5A\"],\"legalName\":\"Pelletterie D & D S.r.l.\",\"vatID\":\"IT06541790488\",\"taxID\":\"06541790488\",\"description\":\"Pelletteria artigianale toscana nata come laboratorio negli anni '90. Specializzata in borse da medico in vera pelle conciata al vegetale, lavorata secondo la tradizione del distretto conciario di Santa Croce sull'Arno. Fondata sul principio \\\"Artigianato, non moda\\\".\",\"slogan\":\"Borse che custodiscono il tempo\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Via Renato Bruschi 138\",\"addressLocality\":\"Sesto Fiorentino\",\"addressRegion\":\"FI\",\"postalCode\":\"50019\",\"addressCountry\":\"IT\"},\"foundingLocation\":{\"@type\":\"Place\",\"name\":\"Santa Croce sull'Arno, Toscana, Italia\",\"address\":{\"@type\":\"PostalAddress\",\"addressLocality\":\"Santa Croce sull'Arno\",\"addressRegion\":\"Toscana\",\"addressCountry\":\"IT\"}},\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"+39 055 4491006\",\"email\":\"info@pelletterieded.com\",\"contactType\":\"customer service\",\"availableLanguage\":[\"Italian\",\"English\",\"Spanish\",\"French\",\"German\"]},\"areaServed\":[{\"@type\":\"Country\",\"name\":\"Italy\"},{\"@type\":\"Place\",\"name\":\"European Union\"}],\"knowsAbout\":[\"Borse da medico in pelle\",\"Doctor bags made in Italy\",\"Tuscan vegetable-tanned leather\",\"Italian artisanal leather goods\",\"Personalized leather bags\",\"Hot-stamping leather personalization\",\"Made in Italy leather craftsmanship\",\"Briefcases for professionals\"],\"hasCredential\":{\"@type\":\"EducationalOccupationalCredential\",\"name\":\"Consorzio Vera Pelle Italiana Conciata al Vegetale\",\"description\":\"Leather sourced from tanneries that are members of the Italian Vegetable-Tanned Genuine Leather Consortium\"},\"makesOffer\":[{\"@type\":\"OfferCatalog\",\"name\":\"Pelletterie D&D leather goods\",\"itemListElement\":[{\"@type\":\"OfferCatalog\",\"name\":\"Borse da medico in pelle\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/borse-da-medico\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Borse donna in pelle toscana\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/donna\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Borse uomo in pelle professionale\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/uomo\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Borse da viaggio in pelle italiana\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/borse-da-viaggio\\\/\"},{\"@type\":\"OfferCatalog\",\"name\":\"Piccola pelletteria italiana\",\"url\":\"https:\\\/\\\/pelletterieded.com\\\/it\\\/categoria-prodotto\\\/extra\\\/\"}]}],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"applicableCountry\":\"IT\",\"returnPolicyCategory\":\"https:\\\/\\\/schema.org\\\/MerchantReturnFiniteReturnWindow\",\"merchantReturnDays\":14}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gallery e cosa dicono di noi - Pelletterie D&amp;D","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pelletterieded.com\/de\/gallery-e-cosa-dicono-di-noi\/","og_locale":"de_DE","og_type":"article","og_title":"Gallery e cosa dicono di noi - Pelletterie D&amp;D","og_url":"https:\/\/pelletterieded.com\/de\/gallery-e-cosa-dicono-di-noi\/","og_site_name":"Pelletterie D&amp;D","article_publisher":"https:\/\/www.facebook.com\/dedpelletterie","article_modified_time":"2022-02-07T17:56:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pelletterieded.com\/de\/gallery-e-cosa-dicono-di-noi\/","url":"https:\/\/pelletterieded.com\/de\/gallery-e-cosa-dicono-di-noi\/","name":"Gallery e cosa dicono di noi - Pelletterie D&amp;D","isPartOf":{"@id":"https:\/\/pelletterieded.com\/de\/#website"},"datePublished":"2022-02-07T17:56:45+00:00","dateModified":"2022-02-07T17:56:46+00:00","breadcrumb":{"@id":"https:\/\/pelletterieded.com\/de\/gallery-e-cosa-dicono-di-noi\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pelletterieded.com\/de\/gallery-e-cosa-dicono-di-noi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pelletterieded.com\/de\/gallery-e-cosa-dicono-di-noi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pelletterie D&amp;D","item":"https:\/\/pelletterieded.com\/de\/home-page-nuova-2021\/"},{"@type":"ListItem","position":2,"name":"Gallery e cosa dicono di noi"}]},{"@type":"WebSite","@id":"https:\/\/pelletterieded.com\/de\/#website","url":"https:\/\/pelletterieded.com\/de\/","name":"Pelletterie D&D","description":"Pelletteria artigianale toscana specializzata in borse in pelle Made in Italy, borse da medico, donna, uomo e viaggio in pelle conciata al vegetale.","publisher":{"@id":"https:\/\/pelletterieded.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pelletterieded.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","LocalBusiness","OnlineStore"],"@id":"https:\/\/pelletterieded.com\/de\/#organization","name":"Pelletterie D&D","alternateName":["D&D Pelletterie","Pelletterie D e D","Pelletterie DED"],"url":"https:\/\/pelletterieded.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pelletterieded.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","contentUrl":"https:\/\/pelletterieded.com\/wp-content\/uploads\/2019\/07\/logo-pelletterie-ded-mail.webp","width":185,"height":200,"caption":"Pelletterie D&D"},"image":{"@id":"https:\/\/pelletterieded.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dedpelletterie","https:\/\/www.instagram.com\/pelletterieded\/","https:\/\/www.feedaty.com\/recensioni\/pelletterieded","https:\/\/www.amazon.it\/stores\/page\/EEBC9051-1D83-453F-A8AE-7FE798E14B5A"],"legalName":"Pelletterie D & D S.r.l.","vatID":"IT06541790488","taxID":"06541790488","description":"Pelletteria artigianale toscana nata come laboratorio negli anni '90. Specializzata in borse da medico in vera pelle conciata al vegetale, lavorata secondo la tradizione del distretto conciario di Santa Croce sull'Arno. Fondata sul principio \"Artigianato, non moda\".","slogan":"Borse che custodiscono il tempo","address":{"@type":"PostalAddress","streetAddress":"Via Renato Bruschi 138","addressLocality":"Sesto Fiorentino","addressRegion":"FI","postalCode":"50019","addressCountry":"IT"},"foundingLocation":{"@type":"Place","name":"Santa Croce sull'Arno, Toscana, Italia","address":{"@type":"PostalAddress","addressLocality":"Santa Croce sull'Arno","addressRegion":"Toscana","addressCountry":"IT"}},"contactPoint":{"@type":"ContactPoint","telephone":"+39 055 4491006","email":"info@pelletterieded.com","contactType":"customer service","availableLanguage":["Italian","English","Spanish","French","German"]},"areaServed":[{"@type":"Country","name":"Italy"},{"@type":"Place","name":"European Union"}],"knowsAbout":["Borse da medico in pelle","Doctor bags made in Italy","Tuscan vegetable-tanned leather","Italian artisanal leather goods","Personalized leather bags","Hot-stamping leather personalization","Made in Italy leather craftsmanship","Briefcases for professionals"],"hasCredential":{"@type":"EducationalOccupationalCredential","name":"Consorzio Vera Pelle Italiana Conciata al Vegetale","description":"Leather sourced from tanneries that are members of the Italian Vegetable-Tanned Genuine Leather Consortium"},"makesOffer":[{"@type":"OfferCatalog","name":"Pelletterie D&D leather goods","itemListElement":[{"@type":"OfferCatalog","name":"Borse da medico in pelle","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/borse-da-medico\/"},{"@type":"OfferCatalog","name":"Borse donna in pelle toscana","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/donna\/"},{"@type":"OfferCatalog","name":"Borse uomo in pelle professionale","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/uomo\/"},{"@type":"OfferCatalog","name":"Borse da viaggio in pelle italiana","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/borse-da-viaggio\/"},{"@type":"OfferCatalog","name":"Piccola pelletteria italiana","url":"https:\/\/pelletterieded.com\/it\/categoria-prodotto\/extra\/"}]}],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","applicableCountry":"IT","returnPolicyCategory":"https:\/\/schema.org\/MerchantReturnFiniteReturnWindow","merchantReturnDays":14}}]}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/pages\/161933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/users\/275"}],"replies":[{"embeddable":true,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/comments?post=161933"}],"version-history":[{"count":0,"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/pages\/161933\/revisions"}],"wp:attachment":[{"href":"https:\/\/pelletterieded.com\/de\/wp-json\/wp\/v2\/media?parent=161933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}